{"id":12455,"date":"2025-07-20T18:42:13","date_gmt":"2025-07-20T16:42:13","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/20\/liran-millenaire-outrage-une-reponse-magistrale-stupefiante-paralysante\/"},"modified":"2025-07-20T18:42:13","modified_gmt":"2025-07-20T16:42:13","slug":"liran-millenaire-outrage-une-reponse-magistrale-stupefiante-paralysante","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/20\/liran-millenaire-outrage-une-reponse-magistrale-stupefiante-paralysante\/","title":{"rendered":"L&rsquo;Iran mill\u00e9naire outrag\u00e9. Une r\u00e9ponse magistrale stup\u00e9fiante, paralysante !"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div style=\"word-wrap:break-word;\">\n<p><strong>Cette guerre contre l\u2019Iran ne peut \u00eatre dissoci\u00e9e de la cause palestinienne. Un peuple d\u00e9pouill\u00e9 de ses terres, par une colonisation de peuplement abjecte qui dure depuis 80 ans\u00a0! Colonis\u00e9 par des groupes, aux origines et langues diverses, rassembl\u00e9s autour d\u2019une cause fallacieuse, orchestr\u00e9e par des malfaiteurs. Un m\u00e9lange de Juifs, de pseudo-convertis et d\u2019aventuriers cupides &#8211; impos\u00e9s par la force des armes pour spolier un peuple &#8211; soutenus par des \u00c9tats malveillants cherchant \u00e0 s\u2019en d\u00e9barrasser d\u2019Europe. La plupart des gouvernants arabes sunnites (surtout du Golfe) ont manifest\u00e9 une l\u00e2chet\u00e9 vis-\u00e0-vis de la Palestine et de l\u2019Iran. Seuls les chiites se \u2018\u2018mouillent\u2019\u2019 dans ce conflit\u00a0!<\/strong><\/p>\n<p> Les nouveaux arrivants, d\u00e9sign\u00e9s sous le nom d\u2019\u00ab\u00a0<i>Isra\u00e9liens<\/i>\u00a0\u00bb, sont constamment abreuv\u00e9s par l\u2019endoctrinement sionistes, sur leur pr\u00e9tendue invincibilit\u00e9. Cependant, ils r\u00e9alisent qu\u2019on leur a fait croire \u00e0 des illusions, suite \u00e0 la puissante riposte iranienne \u00e0 l\u2019agression\u00a0! En provoquant l\u2019Iran, ils se croyaient \u00ab\u00a0lion\u00a0\u00bb face \u00e0 une \u00ab\u00a0hy\u00e8ne\u201d\u00a0; ils se sont retrouv\u00e9s \u00ab\u00a0hy\u00e8ne\u00a0\u00bb affrontant un \u00ab\u00a0lion\u00a0\u00bb\u00a0!<\/p>\n<p>Si Trump est arriv\u00e9 au point de se voir oblig\u00e9 d\u2019intervenir, c\u2019est pour venir \u00e0 la rescousse de son proxy sioniste en d\u00e9route. La strat\u00e9gie de l\u2019Iran \u00e9tait bien plus r\u00e9fl\u00e9chie et \u00e9labor\u00e9e, visant des cibles strat\u00e9giques sensibles, qui allaient conduire \u00e0 l\u2019effondrement de l\u2019entit\u00e9 sioniste\u00a0!<\/p>\n<p>Si le g\u00e9nocidaire Netanyahou, \u00e9duqu\u00e9 dans le s\u00e9rail \u201cjabotinskyste\u201d, feint s\u2019indigner en disant qu\u2019il a \u00e9t\u00e9 \u00ab\u00a0tromp\u00e9 par Trump\u00a0\u00bb, c\u2019est pour se d\u00e9rober de la responsabilit\u00e9 de fin de combat qu\u2019il a lui-m\u00eame r\u00e9clam\u00e9e. En revanche, il r\u00e9v\u00e8le, idiotement, qu\u2019il s\u2019est conduit en v\u00e9ritable proxy avec des armes am\u00e9ricaines. Sinon, il aurait continu\u00e9 ses op\u00e9rations &#8211; de \u00ab\u00a0d\u00e9capitation\u00a0\u00bb (pr\u00e9voyant d\u2019assassiner le guide supr\u00eame, \u00e2g\u00e9 de 86 ans) et de \u00ab\u00a0changement de r\u00e9gime\u00a0\u00bb &#8211; avec sa puissance militaire intrins\u00e8que, sans aide\u00a0! \u00c0 l\u2019heure de l\u2019internet, rien ne se cache. Le monde finit par conna\u00eetre la v\u00e9rit\u00e9 instantan\u00e9ment\u00a0: John Mearsheimer (1) affirme que ce sont les Isra\u00e9liens qui leur ont demand\u00e9 d\u2019arr\u00eater la guerre, car ils \u00e9taient  \u00ab\u00a0en grande difficult\u00e9\u00a0\u00bb. Au neuvi\u00e8me jour, le <i>Wall Street Journal<\/i> (pro-Isra\u00ebl), annonce qu\u2019il ne restait \u00e0 Isra\u00ebl que deux semaines de moyens de d\u00e9fense\u00a0! Selon Larry Johnson, Trump, n\u2019a fait que suivre ce qui est planifi\u00e9 depuis longtemps, pensant que cela marcherait. D\u2019apr\u00e8s lui, ils lui ont vendu un \u2018produit\u2019 qui promettait une victoire militaire incroyable.<\/p>\n<p><strong>Trump est-il intervenu contraint\u00a0?<\/strong><\/p>\n<p>Trump est-il intervenu en fervent ami d\u2019Isra\u00ebl, des sionistes et de cette fripouille corrompue Netanyahou ou bien a-t-il agi contraint\u00a0?<\/p>\n<p>On avance une raison humiliante. Il se peut qu\u2019il soit soumis \u00e0 un chantage\u00a0! Des photos (2) et ICI (3) le montrent avec l\u2019espion isra\u00e9lien Jeffrey Epstein en bonnes compagnies f\u00e9minines. Il serait donc lui aussi sur la liste (disparue) \u00ab\u00a0de clients\u00a0\u00bb\u00a0! Selon Chris Hedges (4), le refus de l\u2019administration Trump de divulguer les dossiers et les vid\u00e9os de l\u2019enqu\u00eate sur Epstein, vise \u00e0 prot\u00e9ger Trump et toute la classe de dirigeants, de politiciens, de milliardaires et de c\u00e9l\u00e9brit\u00e9s. Ils font tous partie du m\u00eame club. Epstein avait install\u00e9 des cam\u00e9ras \u2019espion\u2019 dans ses r\u00e9sidences. <br class=\"autobr\"\/><br \/>\nC\u2019est dans ce contexte que M.\u00a0Araghchi a d\u00fb s\u2019interroger sur le culot de Netanyahou de dicter aux \u00c9tats-Unis ce qu\u2019ils \u00ab\u00a0doivent ou ne doivent pas dire ou faire dans leurs n\u00e9gociations avec l\u2019Iran\u00a0\u00bb entre autres la demande absurde de limitation des missiles iraniens \u00e0&#8230; 480 kilom\u00e8tres\u00a0! Il questionne\u00a0: \u00ab\u00a0que fume exactement Netanyahou\u00a0? Et s\u2019il ne fume rien, quel pouvoir le Mossad d\u00e9tient-il sur la Maison-Blanche\u00a0?\u00a0\u00bb. Trump, dans son for int\u00e9rieur, doit \u00eatre satisfait de la destruction spectaculaire du si\u00e8ge du Mossad.<\/p>\n<p>Bien que victime d\u2019une agression non justifi\u00e9e &#8211; et surtout en phase de lui infliger une d\u00e9faite m\u00e9morable par l\u2019an\u00e9antissement de ses capacit\u00e9s militaires et \u00e9conomiques &#8211; l\u2019Iran, par sagesse islamique, a accept\u00e9 l\u2019arr\u00eat des hostilit\u00e9s propos\u00e9, sans jubilation, ni forfanterie. Curieux qu\u2019un nain biberonn\u00e9 par les USA et une partie de l\u2019Europe brave le lion perse en repos. L\u2019Iran fait 80 fois l\u2019entit\u00e9 sioniste en superficie et en population et cette derni\u00e8re est bien plus dispers\u00e9e en Iran\u00a0: 48\/km\u00b2 contre 480\/km\u00b2.<\/p>\n<p>S\u2019ils crient qu\u2019il \u00ab\u00a0ne reste plus de \u2018nucl\u00e9aire\u2019 en Iran\u00a0\u00bb, c\u2019est qu\u2019il n\u2019y a donc plus rien \u00e0 contr\u00f4ler ou \u00e0 n\u00e9gocier\u00a0! On accable cet Iran depuis au moins 1993 avec cette histoire de \u201cbombe atomique\u201d en ressassant depuis 32 ans les mantras \u201c il l\u2019aura dans X ann\u00e9es \u201d,  dans X mois \u201d, \u201cdans X semaines \u201d, \u201c l\u2019Iran est \u00e0 quelques semaines de la bombe\u00a0\u00bb, \u201cil l\u2019a d\u00e9j\u00e0\u201d, puis ils recommencent\u00a0! On agace l\u2019Iran (et le reste du monde) depuis 32 ans sur cette question. Il ne reste plus qu\u2019un seul moyen, pour l\u2019Iran, de mettre un terme \u00e0 cette obsession maladive.<br class=\"autobr\"\/><br \/>\nRappelons que l\u2019ayatollah Khomeini avait interdit la production et l\u2019usage des armes chimiques\u00a0; m\u00eame agress\u00e9 par la m\u00eame arme funeste par l\u2019Irak. On conna\u00eet les sagesses de l\u2019Islam, mais il oblige aussi \u00e0 se d\u00e9fendre\u00a0! Sans utiliser ces armes par principe, l\u2019ennemi se calmera \u00e0 l\u2019id\u00e9e qu\u2019il peut lui aussi \u00eatre an\u00e9anti s\u2019il en fait usage\u00a0!<\/p>\n<p>\u00c0 notre avis, les Atlantico-sionistes ne l\u00e2cheront pas l\u2019Iran tant qu\u2019il n\u2019aura pas un moyen dissuasif. Ils veulent le d\u00e9cimer de gr\u00e9 ou de force. Tout s\u2019arr\u00eatera net le jour o\u00f9 l\u2019Iran d\u00e9clarera qu\u2019il poss\u00e8de cette arme\u00a0! Comme l\u2019a fait la Cor\u00e9e (qui est maintenant tranquille)\u00a0! Cette histoire de \u00ab\u00a0principe\u00a0\u00bb et de \u00ab\u00a0pacifique\u00a0\u00bb ne tient pas avec ces diables\u00a0! C\u2019est pr\u00e9cis\u00e9ment du fait de ces valeurs et de cette honn\u00eatet\u00e9 iranienne que ces d\u00e9mons, rassur\u00e9s, s\u2019ent\u00eatent dans leur agression\u00a0! Ils n\u2019auraient jamais os\u00e9 attaquer l\u2019Iran s\u2019ils \u00e9taient s\u00fbr qu\u2019il poss\u00e8de cette arme s\u00e9curisante.<\/p>\n<p><strong>L\u2019AIEA, un instrument d\u2019espionnage<\/strong><\/p>\n<p>Rappelons aussi que L\u2019AIEA avait pour mission, en l\u2019Irak, d\u2019en v\u00e9rifier l\u2019existence en collectant des informations militaires pour la CIA et le Mossad. C\u2019est apr\u00e8s s\u2019\u00eatre rassur\u00e9s que l\u2019Irak n\u2019avait pas l\u2019arme nucl\u00e9aire qu\u2019il a \u00e9t\u00e9 attaqu\u00e9 pour \u201c changer le r\u00e9gime \u201d\u00a0! Le m\u00eame calcul a \u00e9t\u00e9 fait pour l\u2019Iran par ces voyous, arrogants et cupides, qui trouvent toujours des \u201c bonus \u201d quand ils comptent seuls. C\u2019\u00e9tait sans compter sur l\u2019intelligence s\u00e9culaire des Perses qui ont capitalis\u00e9 d\u2019autres moyens conventionnels de ripostes bien plus puissants qui ont p\u00e9trifi\u00e9 l\u2019agresseur, l\u2019obligeant \u00e0 qu\u00e9mander un \u201c cessez-le-feu \u201d, m\u00eame hypoth\u00e9tique. En 12 jours, le pays s\u2019\u00e9puisait, les moyens s\u2019amenuisaient et le territoire se vidait de ses habitants qui fuyaient par dizaines de milliers vers l\u2019\u00e9tranger \u00e0 la faveur de leur autre nationalit\u00e9. Sait-on jamais\u00a0! Les nombreux et fameux syst\u00e8mes de d\u00e9fense antimissiles \u00ab\u00a0d\u00f4me de fe r\u00a0\u00bb, \u00ab\u00a0fronde de David\u00a0\u00bb et \u00ab\u00a0THAAD\u00a0\u00bb n\u2019ont pas tenu face \u00e0 la balistique iranienne.<\/p>\n<p>Un maire isra\u00e9lien qui dit n\u2019avoir \u00ab\u00a0jamais vu une telle destruction de ma vie\u00a0\u00bb &#8211; de ce fait m\u00eame les massacres \u00e0 Gaza \u00e0 quelques encablures \u2013 d\u00e9couvre les horreurs de la guerre en les subissant\u00a0! Bien s\u00fbr que le \u2018\u2018p\u00f4vre\u2019\u2019 bougre n\u2019a \u00ab\u00a0jamais rien vu\u00a0\u00bb de pareil puisqu\u2019il ne sort de \u00ab\u00a0sa mairie\u00a0\u00bb que pour les EU ou l\u2019Europe, ses origines\u00a0!<\/p>\n<p>L\u2019Iran est d\u00e9sormais plus incit\u00e9 \u00e0 se doter de l\u2019arme nucl\u00e9aire qu\u2019il ne l\u2019\u00e9tait avant les frappes isra\u00e9lo-\u00e9tasuniennes\u00a0! Il dispose pour cela de moyens, surtout de savants, pour y parvenir en tr\u00e8s peu de temps\u00a0! L\u2019expulsion de l\u2019AIEA d\u2019Iran mettra fin \u00e0 l\u2019espionnage de cette agence. Il faut pr\u00e9ciser que le probl\u00e8me ne vient pas que de \u00ab\u00a0Rafael Grossi\u00a0\u00bb, mais de toute l\u2019institution AIEA &#8211; comme toutes les autres institutions et ONG dites \u00ab\u00a0internationales\u00a0\u00bb. Elle agit en  \u00ab\u00a0cheval de Troie \u00a0\u00bb avec pour mission cach\u00e9e de collecter les renseignements\u00a0! Quant \u00e0 son \u2019\u2019 devoir de changer \u2019\u2019 pour \u00ab\u00a0regagner en cr\u00e9dibilit\u00e9\u00a0\u00bb, sa fin en soi est d\u2019\u00eatre non cr\u00e9dible n\u00a0! Il n\u2019y a que les cr\u00e9dules et les honn\u00eates gens qui se font duper\u00a0! Dans ce sillage, des informations font \u00e9tat d\u2019une d\u00e9claration du d\u00e9put\u00e9 iranien Nabavian affirmant (5) que l\u2019Iran a des preuves que des documents confidentiels remis \u00e0 l\u2019Agence ont \u00e9t\u00e9 transmis par Grossi \u00e0 Isra\u00ebl. Il affirme \u00e9galement qu\u2019ils ont d\u00e9couvert des micropuces dans les chaussures des inspecteurs lorsqu\u2019ils les ont fouill\u00e9s.<\/p>\n<p><strong>Trump un \u00ab\u00a0sauveur\u00a0\u00bb fourbe<\/strong><\/p>\n<p>Un Trump s\u2019autoproclamant \u00ab\u00a0sauveur\u00a0\u00bb, un type imbu de sa personne, versatile et perfide. Plusieurs analystes le qualifient ainsi, et m\u00eame de narcissique. Il est conseill\u00e9 par des personnes plus isra\u00e9liennes qu\u2019am\u00e9ricaines. Comme ses semblables qui l\u2019ont pr\u00e9c\u00e9d\u00e9, d\u00e8s qu\u2019il propose quoi que ce soit de \u00ab\u00a0bon\u00a0\u00bb, c\u2019est qu\u2019il y a danger en pr\u00e9paration. Quant aux menaces r\u00e9currentes de sanctions, il fait souvent marche arri\u00e8re, y revient, puis recule \u00e0 nouveau au point o\u00f9 on l\u2019assimile \u00e0 \u00ab\u00a0un singe jouant avec une grenade\u00a0\u00bb\u00a0! Ne jamais les croire, car un d\u00e9mon est toujours cach\u00e9 dans leur pens\u00e9e. Il est vain d\u2019esp\u00e9rer tirer du miel du \u00ab\u00a0derri\u00e8re\u00a0\u00bb des frelons\u00a0! Malgr\u00e9 les propos de \u00ab\u00a0cessez-le-feu\u00a0\u00bb, l\u2019action militaire se poursuit encore au Moyen-Orient, car ils ont encore les moyens pour exterminer les enfants, les femmes et autres civils de Gaza.<\/p>\n<p>Terminons par le sermon des Iraniens \u00e0 l\u2019endroit d\u2019Isra\u00ebl puis par les \u00ab\u00a0reproches\u00a0\u00bb que certains font \u00e0 la Russie\u00a0:<\/p>\n<p><span class=\"spip-puce ltr\"><b>\u2013<\/b><\/span>\u00a0En Iran, par la voix d\u2019un haut commandant, l\u2019Iran n\u2019aurait engag\u00e9, dans cette guerre de 12 jours, qu\u2019environ 5\u00a0% de sa force d\u00e9fensive. On peut d\u00e9duire que l\u2019Iran avait un stock disponible de missiles et drones suffisant pour tenir plusieurs mois\u00a0! Cette entit\u00e9 sioniste aurait capitul\u00e9 en moins d\u2019un mois si ce n\u2019\u00e9tait le \u201c pr\u00e9cieux \u201d secours de Trump\u00a0! L\u2019Iran n\u2019avait utilis\u00e9 que quelques-unes de ses armes puissantes les 3 derniers jours\u00a0! On pense que si l\u2019Iran, en cas d\u2019une \u00e9ventuelle reprise des attaques, utilise seulement 20% de sa force en missiles, on assisterait \u00e0 un d\u00e9sastre. Il ne resterait plus rien des grandes villes \u201c d\u2019Isra\u00ebl \u201d\u00a0! Selon PressTv, le ministre de la D\u00e9fense, le g\u00e9n\u00e9ral Aziz Nasirzadeh, a d\u00e9clar\u00e9 dans des appels t\u00e9l\u00e9phoniques d\u2019homologues, que les forces arm\u00e9es \u00e9taient pr\u00eates \u00e0 donner une \u00ab\u00a0r\u00e9ponse s\u00e9v\u00e8re \u00e0 tout aventurisme \u00e9ventuel du r\u00e9gime criminel isra\u00e9lien et de ses partisans occidentaux\u00a0\u00bb\u00a0; allant dans le m\u00eame sens que le chef d\u2019\u00e9tat-major Abdolrahim Mousavi qui a averti que toute erreur r\u00e9p\u00e9t\u00e9e aura une r\u00e9ponse \u00ab\u00a0encore plus forte\u00a0\u00bb.<\/p>\n<p><span class=\"spip-puce ltr\"><b>\u2013<\/b><\/span>\u00a0\u00c0 propos des Russes, certains leur reprochent un certain comportement, notamment leur m\u00e9nagement. Les Russes ne m\u00e9nagent personne qui touche \u00e0 leurs int\u00e9r\u00eats strat\u00e9giques, o\u00f9 qu\u2019ils se trouvent. C\u2019est leur r\u00e9alisme, leur pond\u00e9ration, leur pragmatisme et leur sang-froid qui donne l\u2019impression d\u2019une apathie.<\/p>\n<p>Contrairement aux Isra\u00e9liens qui comptaient sur l\u2019aide des EU, les Russes savaient que l\u2019Iran, seul, allait leur infliger une d\u00e9faite. De plus, l\u2019Iran, par souci de souverainet\u00e9, n\u2019avait pas demand\u00e9 d\u2019aide \u00e0 Moscou. Mais elle s\u2019est fix\u00e9 la limite, car l\u2019Iran est un partenaire \u00ab\u00a0cl\u00e9\u00a0\u00bb.<\/p>\n<p>Cela peut changer si les limites du tol\u00e9rable sont franchies, les autorit\u00e9s russes ne cessent d\u2019avertir qu\u2019il n\u2019y aura pas de limites de leur c\u00f4t\u00e9\u00a0! La Russie (comme la Chine) a des int\u00e9r\u00eats strat\u00e9giques intangibles en Iran.<\/p>\n<p>\u00c0 bon entendeur\u00a0!<br class=\"autobr\"\/><br \/>\n<strong>Amar Djerrad<\/strong><\/p>\n<hr class=\"spip\"\/>\n<p><strong>Notes<\/strong>\u00a0:<br class=\"autobr\"\/><br \/>\n(1) <a target=\"_blank\" href=\"https:\/\/vkvideo.ru\/video-228568258_456292608\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/vkvideo.ru\/video-228568258_456292608<\/a>\u00a0?<br class=\"autobr\"\/><br \/>\n(2) <a target=\"_blank\" href=\"https:\/\/reseauinternational.net\/encore-une-semaine-memorable-a-washington-ou-pas\/\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/reseauinternational.net\/encore-une-semaine-memorable-a-washington-ou-pas\/<\/a><br class=\"autobr\"\/><br \/>\n(3) <a target=\"_blank\" href=\"https:\/\/i0.wp.com\/reseauinternational.net\/wp-content\/uploads\/2025\/07\/Trumpette-dans-ses-frasques-1752413305.7286.jpg\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/i0.wp.com\/reseauinternational.net\/wp-content\/uploads\/2025\/07\/Trumpette-dans-ses-frasques-1752413305.7286.jpg<\/a>\u00a0?<br class=\"autobr\"\/><br \/>\n(4) <a target=\"_blank\" href=\"https:\/\/www.mondialisation.ca\/trump-epstein-et-letat-profond\/5700262\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/www.mondialisation.ca\/trump-epstein-et-letat-profond\/5700262<\/a>\u00a0?<br class=\"autobr\"\/><br \/>\n(5) <a target=\"_blank\" href=\"https:\/\/reseauinternational.net\/nous-avons-decouvert-des-micro-puces-de-surveillance-dissimulees-sur-les-inspecteurs-de-laiea\/\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/reseauinternational.net\/nous-avons-decouvert-des-micro-puces-de-surveillance-dissimulees-sur-les-inspecteurs-de-laiea\/<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.legrandsoir.info\/l-iran-millenaire-outrage-une-reponse-magistrale-stupefiante-paralysante.html\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette guerre contre l\u2019Iran ne peut \u00eatre dissoci\u00e9e de la cause palestinienne. Un peuple d\u00e9pouill\u00e9 de ses terres, par une colonisation de peuplement abjecte qui dure depuis 80 ans\u00a0! Colonis\u00e9&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12455"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12456"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}