{"id":12498,"date":"2025-07-21T12:55:31","date_gmt":"2025-07-21T10:55:31","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/intelligence-artificielle-meta-refuse-de-signer-le-code-de-conduite-de-la-commission-europeenne\/"},"modified":"2025-07-21T12:55:31","modified_gmt":"2025-07-21T10:55:31","slug":"intelligence-artificielle-meta-refuse-de-signer-le-code-de-conduite-de-la-commission-europeenne","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/intelligence-artificielle-meta-refuse-de-signer-le-code-de-conduite-de-la-commission-europeenne\/","title":{"rendered":"Intelligence artificielle: Meta refuse de signer le code de conduite de la Commission europ\u00e9enne"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Meta s\u2019oppose toujours plus ouvertement \u00e0 la l\u00e9gislation europ\u00e9enne. Deux semaines apr\u00e8s avoir fait part de sa d\u00e9cision de contester devant la justice europ\u00e9enne une amende de 200 millions d\u2019euros pour non-respect des r\u00e8gles sur l\u2019utilisation des donn\u00e9es personnelles, dans le cadre du Digital Markets Act (DMA), la firme californienne a annonc\u00e9 son intention de ne pas signer le code de bonnes pratiques de l\u2019UE pour les IA \u00e0 usage g\u00e9n\u00e9ral (GPAI). \u201cL\u2019Europe fait fausse route en mati\u00e8re d\u2019IA\u201d, estime la Tech dirig\u00e9e par Mark Zuckerberg.<\/p>\n<p>L\u2019IA Act, adopt\u00e9 en 2024, est le premier cadre juridique global que l\u2019Union europ\u00e9enne consacre \u00e0 la r\u00e9gulation des syst\u00e8mes d\u2019intelligence artificielle. Il repose sur une classification des syst\u00e8mes d\u2019IA selon leur niveau de risque et impose des obligations techniques et juridiques proportionnellement \u00e0 ces diff\u00e9rents niveaux. Les syst\u00e8mes jug\u00e9s inacceptables, comme la manipulation cognitive \u00e0 grande \u00e9chelle ou la reconnaissance faciale en temps r\u00e9el dans l\u2019espace public, sont interdits.<\/p>\n<p><strong>L\u2019IA \u201cfrein\u00e9e\u201d en Europe, selon Meta<\/strong><\/p>\n<p>D\u00e8s son adoption, l\u2019IA Act a \u00e9t\u00e9 critiqu\u00e9 \u00e0 la fois par l\u2019industrie technologique, des groupes de d\u00e9fense des droits num\u00e9riques, et certains \u00c9tats membres. Les grandes entreprises du secteur d\u00e9noncent une r\u00e9gulation trop lourde qui pourrait freiner l\u2019innovation en Europe, au profit de concurrents am\u00e9ricains ou chinois moins encadr\u00e9s. Plusieurs reprochent \u00e9galement un manque de clart\u00e9 dans l\u2019application des r\u00e8gles aux mod\u00e8les d\u2019IA dits \u201c\u00e0 usage g\u00e9n\u00e9ral\u201d, comme les grands mod\u00e8les de langage.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>En parall\u00e8le, la Commission europ\u00e9enne a mis en place un code de conduite non contraignant, en coordination avec les entreprises du secteur, pour encadrer d\u00e8s \u00e0 pr\u00e9sent les pratiques li\u00e9es \u00e0 l\u2019IA g\u00e9n\u00e9rative et pr\u00e9parer l\u2019entr\u00e9e en vigueur progressive du texte. Ce code, dont la version finale a \u00e9t\u00e9 publi\u00e9e le 10 juillet, se base sur des principes de transparence, de tra\u00e7abilit\u00e9 et de gestion des risques pour anticiper les obligations l\u00e9gales tout en \u00e9vitant une application imm\u00e9diate trop brutale pour le secteur.<\/p>\n<p>Si la soci\u00e9t\u00e9 fran\u00e7aise Mistral AI et le cr\u00e9ateur de ChatGPT, OpenAI, ont annonc\u00e9 qu\u2019ils signeraient le code, Meta rechigne \u00e0 faire pareil. Le groupe californien a annonc\u00e9 qu\u2019il ne signera pas le code des bonnes pratiques de l\u2019UE pour les IA \u00e0 usage g\u00e9n\u00e9ral (GPAI).<\/p>\n<p>C\u2019est le directeur des affaires internationales de Meta, Joel Kaplan, qui en a fait l\u2019annonce. \u201cLe Code de conduite de la Commission europ\u00e9enne pour les mod\u00e8les GPAI \u00e9touffera le d\u00e9veloppement et le d\u00e9ploiement des mod\u00e8les d\u2019IA de pointe, et freinera la croissance \u00e9conomique de l\u2019Europe. Meta ne peut pas le signer\u201d, a-t-il \u00e9crit sur un post X contenant le communiqu\u00e9 int\u00e9gral.<\/p>\n<p>De son avis, \u201cl\u2019Europe prend une mauvaise direction concernant l\u2019IA. Nous avons examin\u00e9 attentivement le Code de conduite (&#8230;) qui introduit un certain nombre d\u2019incertitudes juridiques pour les d\u00e9veloppeurs de mod\u00e8les, ainsi que des mesures qui vont bien au-del\u00e0 du champ d\u2019application de l\u2019AI Act\u201d, estime-t-il.<\/p>\n<p>Rappelant que \u201cplus t\u00f4t ce mois-ci, plus de 40 des plus grandes entreprises europ\u00e9ennes ont sign\u00e9 une lettre demandant \u00e0 la Commission de \u00ab\u00a0stopper le compte \u00e0 rebours\u00a0\u00bb dans sa mise en \u0153uvre\u201d, il a ajout\u00e9 que Meta partageait \u201cles pr\u00e9occupations soulev\u00e9es par ces entreprises selon lesquelles cette r\u00e9glementation excessive freinera le d\u00e9veloppement et le d\u00e9ploiement des mod\u00e8les d\u2019IA de pointe en Europe\u201d.<\/p>\n<p><strong>Des relations d\u00e9j\u00e0 tendues<\/strong><span class=\"Apple-converted-space\"><strong>\u00a0<\/strong><\/span><\/p>\n<p>La d\u00e9cision de Meta a fait r\u00e9agir des d\u00e9put\u00e9s europ\u00e9ens, qui rejettent l\u2019argument de la soci\u00e9t\u00e9 am\u00e9ricaine selon lequel le code \u201cva au-del\u00e0 de la loi sur l\u2019IA\u201d. \u201cLe fait que Meta ne souhaite pas soutenir cette norme minimale est un signal fatal pour la transparence, la s\u00e9curit\u00e9 et la responsabilit\u00e9 europ\u00e9enne\u201d, a ajout\u00e9 Axel Voss, membre du Parti populaire europ\u00e9en (PPE).<\/p>\n<p>La Commission avait averti que les entreprises qui ne signeraient pas le code pourraient faire l\u2019objet d\u2019un contr\u00f4le plus strict de leur conformit\u00e9 avec l\u2019AI Act. Ceci pourrait aggraver les conflits entre Meta et Bruxelles, dont la relation est d\u00e9j\u00e0 tendue.<\/p>\n<p>En avril 2025, la Commission europ\u00e9enne a inflig\u00e9 une amende de 200 millions d&rsquo;euros \u00e0 Meta pour ne pas avoir respect\u00e9 les r\u00e8gles du Digital Markets Act (DMA) encadrant l&rsquo;utilisation des donn\u00e9es personnelles des utilisateurs. Cette sanction, la premi\u00e8re \u00e0 \u00eatre prononc\u00e9e dans le cadre du nouveau r\u00e8glement, vise le mod\u00e8le controvers\u00e9 \u201cpayer ou consentir\u201d propos\u00e9 par Meta, qui impose aux usagers de Facebook et Instagram de choisir entre payer un abonnement pour ne pas \u00eatre cibl\u00e9s par la publicit\u00e9 ou accepter que leurs donn\u00e9es soient utilis\u00e9es \u00e0 des fins de profilage publicitaire.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Bruxelles a consid\u00e9r\u00e9 que cette alternative for\u00e7ait la main des utilisateurs et ne r\u00e9pondait pas aux exigences europ\u00e9ennes relatives \u00e0 la libert\u00e9 de consentement. Meta a imm\u00e9diatement contest\u00e9 la d\u00e9cision, qualifiant l\u2019amende d&rsquo;\u201dincorrecte et ill\u00e9gale\u201d et annon\u00e7ant faire appel devant le Tribunal de l\u2019Union europ\u00e9enne<\/p>\n<\/div>\n<p><script>(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = \"\/\/connect.facebook.net\/fr_FR\/sdk.js#xfbml=1&version=v2.3\";  fjs.parentNode.insertBefore(js, fjs);}(document, \"script\", \"facebook-jssdk\"));<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.francesoir.fr\/societe-science-tech\/intelligence-artificielle-meta-refuse-de-signer-le-code-de-conduite-de-la\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meta s\u2019oppose toujours plus ouvertement \u00e0 la l\u00e9gislation europ\u00e9enne. Deux semaines apr\u00e8s avoir fait part de sa d\u00e9cision de contester devant la justice europ\u00e9enne une amende de 200 millions d\u2019euros&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12498"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12499"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}