{"id":12513,"date":"2025-07-21T17:52:43","date_gmt":"2025-07-21T15:52:43","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/la-semaine-de-4-jours-meilleure-pour-la-sante-et-la-productivite\/"},"modified":"2025-07-21T17:52:43","modified_gmt":"2025-07-21T15:52:43","slug":"la-semaine-de-4-jours-meilleure-pour-la-sante-et-la-productivite","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/la-semaine-de-4-jours-meilleure-pour-la-sante-et-la-productivite\/","title":{"rendered":"La semaine de 4 jours, meilleure pour la sant\u00e9 et la productivit\u00e9"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/25-07-21b_1_1_-d68fb.jpg?1753108200\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Une \u00e9tude d\u00e9montre les effets positifs d&rsquo;une semaine \u00e0 quatre jours de travail sans baisse de salaire, qui permet une am\u00e9lioration de la sant\u00e9 physique et mentale, tout en travaillant de fa\u00e7on plus efficace. <br class=\"autobr\" \/> L&rsquo;id\u00e9e n&rsquo;est certes pas \u00e0 l&rsquo;ordre du jour de nos dirigeants, plus enclins \u00e0 supprimer des jours f\u00e9ri\u00e9s qu&rsquo;\u00e0 envisager une r\u00e9duction du temps de travail. Mais dans le monde acad\u00e9mique, la semaine de quatre jours fait son chemin, prouvant ses vertus \u00e0 chaque nouvelle \u00e9tude. La derni\u00e8re\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/La-semaine-de-4-jours-meilleure-pour-la-sante-et-la-productivite?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Autres-infos\" rel=\"directory\">Info<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Quotidien\" rel=\"tag\">Quotidien<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Sante\" rel=\"tag\">Sant\u00e9<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Social\" rel=\"tag\">Social<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/La-semaine-de-4-jours-meilleure-pour-la-sante-et-la-productivite\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9tude d\u00e9montre les effets positifs d&rsquo;une semaine \u00e0 quatre jours de travail sans baisse de salaire, qui permet une am\u00e9lioration de la sant\u00e9 physique et mentale, tout en travaillant&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12513","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12513"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12513\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}