{"id":12527,"date":"2025-07-21T22:48:42","date_gmt":"2025-07-21T20:48:42","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/pourquoi-des-soldats-israeliens-se-suicident-ils\/"},"modified":"2025-07-21T22:48:42","modified_gmt":"2025-07-21T20:48:42","slug":"pourquoi-des-soldats-israeliens-se-suicident-ils","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/21\/pourquoi-des-soldats-israeliens-se-suicident-ils\/","title":{"rendered":"Pourquoi des soldats isra\u00e9liens se suicident-ils ?"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<ol class=\"campaign-loop campaign-list\">\n<li id=\"campaign-455508\" class=\"post-455508 campaign type-campaign status-publish hentry campaign-has-goal campaign-has-not-achieved-goal campaign-has-end-date campaign-has-not-ended\">\n\t<a target=\"_blank\" href=\"https:\/\/reseauinternational.net\/campaigns\/campagne-de-dons-mai-2025\/\"><\/p>\n<h3>Campagne de dons \u2013 Mai-Juin 2025<\/h3>\n<p>\t\t\t<\/a><\/p>\n<p>\n\tChers amis lecteurs, Nous faisons \u00e0 nouveau appel \u00e0 vous pour une nouvelle campagne de dons. Votre soutien nous est indispensable pour continuer \u00e0 vous fournir le meilleur de l\u2019information internationale alternative. C\u2019est gr\u00e2ce \u00e0 vos dons que nous pourrons maintenir le cap pour une information plurielle et r\u00e9ellement alternative. Nous comptons sur vous.<\/p>\n<p>\n<span class=\"amount\">20 129,00\u00a0\u20ac<\/span> de l\u2019objectif de <span class=\"goal-amount\">25 000,00\u00a0\u20ac<\/span> atteint<\/p>\n<\/li>\n<\/ol>\n<p>par <strong>Al-Manar<\/strong><\/p>\n<p>La hausse des cas de suicide dans les rangs des soldats isra\u00e9liens d\u00e9mobilis\u00e9s, une fois de retour \u00e0 la vie normale inqui\u00e8te. Selon les m\u00e9dias isra\u00e9liens, les suicides dans l\u2019arm\u00e9e d\u2019occupation sont pass\u00e9 de 17 cas en 2023, \u00e0 21 en 2024 et \u00e0 16 nouveaux cas jusqu\u2019\u00e0 la mi-2025.<\/p>\n<p>Le dernier a tent\u00e9 de mettre fin \u00e0 ses jours lors d\u2019un entra\u00eenement dans le sud de la Palestine occup\u00e9e.<\/p>\n<p>Des experts isra\u00e9liens cherchent \u00e0 en d\u00e9crypter les causes.<\/p>\n<h5 class=\"wp-block-heading\"><strong>6000 demandes d\u2019aide en un mois<\/strong><\/h5>\n<p>Dans un rapport d\u2019enqu\u00eate publi\u00e9 par le site d\u2019information isra\u00e9lien <em>Walla<\/em>, il a \u00e9t\u00e9 constat\u00e9 que le Centre d\u2019intervention d\u2019urgence \u00abEran\u00bb a re\u00e7u plus de 6000 demandes d\u2019aide psychologique de la part de soldats et de femmes soldats de l\u2019arm\u00e9e en seulement un mois, dont 28% \u00e9taient li\u00e9es \u00e0 une d\u00e9tresse psychologique grave, 20% \u00e0 l\u2019anxi\u00e9t\u00e9 et aux traumatismes, 32% au sentiment de solitude totale, tandis que 10% ont signal\u00e9 des probl\u00e8mes dans les relations personnelles.<\/p>\n<p>Pour <em>Walla<\/em>, Eyal Fruchter, ancien chef du syst\u00e8me de sant\u00e9 mentale dans l\u2019arm\u00e9e d\u2019occupation, a soulign\u00e9 que les suicides sont une cha\u00eene tragique qui n\u00e9cessite une intervention urgente. Les r\u00e9servistes courent un double risque, notamment la d\u00e9sint\u00e9gration familiale, l\u2019isolement, l\u2019acc\u00e8s facile aux armes et les exp\u00e9riences traumatisantes non trait\u00e9es, a-t-il ajout\u00e9. Il a not\u00e9 que l\u2019\u00e9largissement des programmes de pr\u00e9vention pour inclure les r\u00e9serves \u00e9tait positif, mais a averti qu\u2019une couverture m\u00e9diatique excessive pourrait provoquer une \u00ab<em>infection suicidaire<\/em>\u00bb chez les soldats.<\/p>\n<h5 class=\"wp-block-heading\"><strong>Crises invisibles<\/strong><\/h5>\n<p>Rona Ackerman, travailleuse sociale et directrice g\u00e9n\u00e9rale adjointe du Centre Ella pour le soutien psychologique en cas de perte et de traumatisme, a d\u00e9clar\u00e9 que les batailles cr\u00e9aient des \u00ab<em>crises invisibles<\/em>\u00bb dont il est difficile de parler. Les soldats per\u00e7us comme forts ont du mal \u00e0 reconna\u00eetre les sentiments d\u2019\u00e9puisement ou de perte qui surgissent apr\u00e8s la bataille, et l\u2019\u00e9cart entre leur image de soi et leur r\u00e9alit\u00e9 psychologique peut conduire \u00e0 une crise identitaire.<\/p>\n<p>M\u00eame constat de la part de Sherry Daniels, directrice professionnelle d\u2019Eran. Elle a d\u00e9clar\u00e9 que la stigmatisation associ\u00e9e \u00e0 la sant\u00e9 mentale emp\u00eache les soldats de demander de l\u2019aide, ce qui est consid\u00e9r\u00e9 comme un signe de vuln\u00e9rabilit\u00e9.<\/p>\n<p>Daniels a expliqu\u00e9 que la culture militaire favorise le silence, car on demande aux soldats de r\u00e9primer leurs \u00e9motions, de travailler sous pression et de maintenir leurs performances. Ces \u00ab<em>vertus combattantes<\/em>\u00bb, selon elle, se transforment en obstacles psychologiques lors du retour \u00e0 la vie quotidienne. Elle a ajout\u00e9 que de nombreux soldats ne reconnaissaient m\u00eame pas leurs sentiments.<\/p>\n<h5 class=\"wp-block-heading\"><strong>Des suicides auraient pu \u00eatre \u00e9vit\u00e9s<\/strong><\/h5>\n<p>Nadav Wirch, pr\u00e9sident du forum Traumatized by Combat et l\u2019un des soldats souffrant de traumatismes de combat, a d\u00e9clar\u00e9 \u00e0 Walla que la plupart des suicides auraient pu \u00eatre \u00e9vit\u00e9s, en raison de signes avant-coureurs tels que la recherche d\u2019aide ou des changements psychologiques \u00e9vidents. La lenteur du syst\u00e8me bureaucratique, la n\u00e9gligence et le manque de personnel sp\u00e9cialis\u00e9 conduisent \u00e0 la marginalisation des cas, a-t-il ajout\u00e9, car de nombreux soldats ne b\u00e9n\u00e9ficient pas d\u2019un v\u00e9ritable suivi psychologique m\u00eame apr\u00e8s avoir \u00e9t\u00e9 soign\u00e9s.<\/p>\n<h5 class=\"wp-block-heading\"><strong>La violence se retourne contre soi<\/strong><\/h5>\n<p>Curieusement, ces diagnostics \u00e9vitent d\u2019\u00e9tudier une cause \u00e9ventuelle qui scrute le lien entre la violence inou\u00efe exerc\u00e9e par ces soldats contre la population gazaouie et leur propension au suicide.<\/p>\n<p>\u00ab<em>La repr\u00e9sentation du suicidaire \u00e9tait souvent celle d\u2019une personne d\u00e9courag\u00e9e, taciturne, repli\u00e9e sur elle-m\u00eame. Si ce portrait correspond en effet au portrait de certaines personnes qui s\u2019enl\u00e8vent la vie, plus particuli\u00e8rement chez les a\u00een\u00e9s, il omet de prendre en ligne de compte le caract\u00e8re impulsif et agressif qui anime une grande partie des personnes qui s\u2019enl\u00e8vent la vie<\/em>\u00bb, constate une \u00e9tude publi\u00e9e par Presse de l\u2019Universit\u00e9 de Montr\u00e9al intitul\u00e9e : \u00ab<em><a target=\"_blank\" href=\"https:\/\/books.openedition.org\/pum\/10640?lang=en\" target=\"_blank\" rel=\"noopener\" title=\"\">Caract\u00e9ristiques personnelles associ\u00e9es au suicide<\/a><\/em>\u00bb.<\/p>\n<p>Elle rapporte les conclusions d\u2019une th\u00e8se publi\u00e9e en 1954 par Henry et Short selon lesquels 10% \u00e0 20% des personnes qui commettent des gestes suicidaires graves ont d\u00e9j\u00e0 pos\u00e9 un acte violent grave \u00e0 l\u2019\u00e9gard d\u2019autrui. Et pr\u00e8s d\u2019un tiers des personnes violentes ont d\u00e9j\u00e0 tent\u00e9 de s\u2019enlever la vie.<\/p>\n<p>Selon l\u2019argument d\u00e9velopp\u00e9 par Van Heeringen, Hawton et Williams les gens impulsifs et agressifs finissent par payer pour les torts inflig\u00e9s aux autres et pour l\u2019absence de recours \u00e0 d\u2019autres solutions pour s\u2019en sortir. Pour eux, la tendance \u00e0 se mettre en col\u00e8re et \u00e0 se rebeller finit par avoir des limites parce que les sautes d\u2019humeur repr\u00e9sentent une fuite par rapport aux probl\u00e8mes et l\u2019absence de solutions. Apr\u00e8s un certain temps, l\u2019individu est coinc\u00e9 et ne peut plus s\u2019en sortir aussi facilement. C\u2019est alors que naissent le d\u00e9couragement, la d\u00e9pression et le d\u00e9sespoir et que la violence finit par se retourner contre soi.<\/p>\n<p>source : <a target=\"_blank\" href=\"https:\/\/french.almanar.com.lb\/3344805\" target=\"_blank\" rel=\"noopener\" title=\"\">Al-Manar<\/a><\/p>\n<div class=\"sharedaddy sd-block sd-like jetpack-likes-widget-wrapper jetpack-likes-widget-unloaded\" id=\"like-post-wrapper-237719536-472268-687eb12aaf305\" data-src=\"https:\/\/widgets.wp.com\/likes\/?ver=14.8#blog_id=237719536&amp;post_id=472268&amp;origin=reseauinternational.net&amp;obj_id=237719536-472268-687eb12aaf305\" data-name=\"like-post-frame-237719536-472268-687eb12aaf305\" data-title=\"Aimer ou rebloguer\">\n<h3 class=\"sd-title\">J\u2019aime \u00e7a\u00a0:<\/h3>\n<p><span class=\"button\"><span>J\u2019aime<\/span><\/span> <span class=\"loading\">chargement\u2026<\/span><\/p>\n<p><span class=\"sd-text-color\"\/><a target=\"_blank\" class=\"sd-link-color\"\/><\/div>\n<p><meta itemscope=\"\" itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/WebPage\" itemid=\"https:\/\/reseauinternational.net\/pourquoi-des-soldats-israeliens-se-suicident-ils\/\"\/><meta itemprop=\"headline\" content=\"Pourquoi des soldats isra\u00e9liens se suicident-ils ?\"\/><span style=\"display: none;\" itemprop=\"author\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/Person\"><meta itemprop=\"name\" content=\"R\u00e9seau International\"\/><\/span><span style=\"display: none;\" itemprop=\"image\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/i0.wp.com\/reseauinternational.net\/wp-content\/uploads\/2025\/07\/Sans-titre-25-8.png?fit=800%2C467&amp;quality=100&amp;ssl=1\"\/><meta itemprop=\"width\" content=\"800\"\/><meta itemprop=\"height\" content=\"467\"\/><\/span><span style=\"display: none;\" itemprop=\"publisher\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/Organization\"><span style=\"display: none;\" itemprop=\"logo\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/reseauinternational.net\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-2022-06-14-a\u0300-16.51.07.png\"\/><\/span><meta itemprop=\"name\" content=\"R\u00e9seau International\"\/><\/span><meta itemprop=\"datePublished\" content=\"2025-07-21T12:12:04+00:00\"\/><meta itemprop=\"dateModified\" content=\"2025-07-21T12:13:10+00:00\"\/><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/reseauinternational.net\/pourquoi-des-soldats-israeliens-se-suicident-ils\/\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campagne de dons \u2013 Mai-Juin 2025 Chers amis lecteurs, Nous faisons \u00e0 nouveau appel \u00e0 vous pour une nouvelle campagne de dons. Votre soutien nous est indispensable pour continuer \u00e0&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12527"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12528"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}