{"id":12548,"date":"2025-07-22T08:11:39","date_gmt":"2025-07-22T06:11:39","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/novethic-le-media-public-de-la-finance-durable-rachete-par-un-acteur-prive\/"},"modified":"2025-07-22T08:11:39","modified_gmt":"2025-07-22T06:11:39","slug":"novethic-le-media-public-de-la-finance-durable-rachete-par-un-acteur-prive","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/novethic-le-media-public-de-la-finance-durable-rachete-par-un-acteur-prive\/","title":{"rendered":"Novethic, le m\u00e9dia public de la \u00ab\u00a0finance durable\u00a0\u00bb, rachet\u00e9 par un acteur priv\u00e9"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/novethoc-4375d.jpg?1753104635\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Cr\u00e9\u00e9 en 2001, le m\u00e9dia Novethic a indiqu\u00e9 le 18\u00a0juillet avoir \u00e9t\u00e9 rachet\u00e9 par <span class=\"caps\">AEF<\/span>\u00a0info, une agence de presse sp\u00e9cialis\u00e9e dans le secteur de l&rsquo;\u00e9ducation. Le Syndicat national du journalisme (<span class=\"caps\">SNJ<\/span>) a aussit\u00f4t a d\u00e9plor\u00e9 dans un communiqu\u00e9 l&rsquo;abandon de ce \u00ab<small class=\"fine d-inline\">\u00a0<\/small>m\u00e9dia public d&rsquo;information sur la transition \u00e9cologique<small class=\"fine d-inline\">\u00a0<\/small>\u00bb par la Caisse des d\u00e9p\u00f4ts, unique actionnaire du m\u00e9dia. <br class=\"autobr\" \/><br \/>\nSi Novethic ne dispara\u00eet pas, il perd n\u00e9anmoins sa subvention, une \u00ab<small class=\"fine d-inline\">\u00a0<\/small>garantie de son ind\u00e9pendance, au profit d&rsquo;un mod\u00e8le payant\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Novethic-le-media-public-de-la-finance-durable-rachete-par-un-acteur-prive?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Breves-20\" rel=\"directory\">En bref<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Medias\" rel=\"tag\">M\u00e9dias<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/Novethic-le-media-public-de-la-finance-durable-rachete-par-un-acteur-prive\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9\u00e9 en 2001, le m\u00e9dia Novethic a indiqu\u00e9 le 18\u00a0juillet avoir \u00e9t\u00e9 rachet\u00e9 par AEF\u00a0info, une agence de presse sp\u00e9cialis\u00e9e dans le secteur de l&rsquo;\u00e9ducation. Le Syndicat national du journalisme&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12548","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12548"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12548\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}