{"id":12579,"date":"2025-07-22T19:14:41","date_gmt":"2025-07-22T17:14:41","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/dans-cette-commune-la-transition-ecologique-est-en-marche-depuis-30-ans\/"},"modified":"2025-07-22T19:14:41","modified_gmt":"2025-07-22T17:14:41","slug":"dans-cette-commune-la-transition-ecologique-est-en-marche-depuis-30-ans","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/dans-cette-commune-la-transition-ecologique-est-en-marche-depuis-30-ans\/","title":{"rendered":"Dans cette commune, la transition \u00e9cologique est en marche depuis 30 ans"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/1_img_20250217_111644_groupe_et_sourire_-f60b5.jpg?1753192801\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Dans la commune de Loos-en-Gohelle, le mod\u00e8le de participation citoyenne qui combine chantiers participatifs, monnaie locale et s\u00e9curit\u00e9 sociale alimentaire est rentr\u00e9 dans les m\u0153urs. Un succ\u00e8s bas\u00e9 sur l&rsquo;accessibilit\u00e9 populaire. <br class=\"autobr\" \/><br \/>\nLoos-en-Gohelle (Pas-de-Calais), reportage <br class=\"autobr\" \/><br \/>\nLes maisons en brique, les terrils jumeaux \u00e0 l&rsquo;horizon, l&rsquo;odeur des frites et la \u00ab<small class=\"fine d-inline\">\u00a0<\/small>ducasse<small class=\"fine d-inline\">\u00a0<\/small>\u00bb \u2014\u00a0f\u00eate foraine\u00a0\u2014 sur la place principale ne mentent pas\u00a0: \u00e0 Loos-en-Gohelle, on est plus que jamais \u00ab<small class=\"fine d-inline\">\u00a0<\/small>dins ch&rsquo;Nord<small class=\"fine d-inline\">\u00a0<\/small>\u00bb.\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Dans-l-ancien-bassin-minier-cette-commune-a-reussi-a-faire-aimer-l-ecologie?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Reportage\" rel=\"directory\">Reportage<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Alternatives\" rel=\"tag\">Alternatives<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/Dans-l-ancien-bassin-minier-cette-commune-a-reussi-a-faire-aimer-l-ecologie\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la commune de Loos-en-Gohelle, le mod\u00e8le de participation citoyenne qui combine chantiers participatifs, monnaie locale et s\u00e9curit\u00e9 sociale alimentaire est rentr\u00e9 dans les m\u0153urs. Un succ\u00e8s bas\u00e9 sur l&rsquo;accessibilit\u00e9&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12579","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12579"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12579\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}