{"id":12592,"date":"2025-07-22T23:39:05","date_gmt":"2025-07-22T21:39:05","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/megafeux-au-canada-lequivalent-de-deux-fois-la-belgique-parti-en-fumee\/"},"modified":"2025-07-22T23:39:05","modified_gmt":"2025-07-22T21:39:05","slug":"megafeux-au-canada-lequivalent-de-deux-fois-la-belgique-parti-en-fumee","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/22\/megafeux-au-canada-lequivalent-de-deux-fois-la-belgique-parti-en-fumee\/","title":{"rendered":"M\u00e9gafeux au Canada\u00a0: l&#039;\u00e9quivalent de deux fois la Belgique parti en fum\u00e9e"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/afp__20250603__493n9np__v1__highres__canadaclimateweatherfire-67168.jpg?1753190729\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Les incendies ont d\u00e9j\u00e0 d\u00e9truit une superficie foresti\u00e8re \u00e9quivalente \u00e0 celle de la Croatie cette ann\u00e9e au Canada. Soit pr\u00e8s de 6\u00a0millions d&rsquo;hectares br\u00fbl\u00e9s, alors que le pays entre seulement dans la p\u00e9riode la plus \u00e0 risque, selon une mise \u00e0 jour des autorit\u00e9s vendredi 18\u00a0juillet. Les autorit\u00e9s d\u00e9nombrent plus de 560 feux actuellement incontr\u00f4lables. <br class=\"autobr\" \/><br \/>\nLa saison des feux 2025 a \u00e9t\u00e9 particuli\u00e8rement pr\u00e9coce en raison de la s\u00e9cheresse et des temp\u00e9ratures sup\u00e9rieures \u00e0 la normale. Elle est\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Megafeux-au-Canada-une-superficie-equivalente-a-la-Croatie-est-partie-en-fumee?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Breves-20\" rel=\"directory\">En bref<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/International\" rel=\"tag\">Monde<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Megafeux\" rel=\"tag\">Incendies<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/Megafeux-au-Canada-une-superficie-equivalente-a-la-Croatie-est-partie-en-fumee\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les incendies ont d\u00e9j\u00e0 d\u00e9truit une superficie foresti\u00e8re \u00e9quivalente \u00e0 celle de la Croatie cette ann\u00e9e au Canada. Soit pr\u00e8s de 6\u00a0millions d&rsquo;hectares br\u00fbl\u00e9s, alors que le pays entre seulement&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12592","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12592"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12592\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}