{"id":12627,"date":"2025-07-23T12:50:34","date_gmt":"2025-07-23T10:50:34","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/23\/interpol-leve-la-notice-rouge-visant-paul-watson-le-defenseur-des-baleines\/"},"modified":"2025-07-23T12:50:34","modified_gmt":"2025-07-23T10:50:34","slug":"interpol-leve-la-notice-rouge-visant-paul-watson-le-defenseur-des-baleines","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/23\/interpol-leve-la-notice-rouge-visant-paul-watson-le-defenseur-des-baleines\/","title":{"rendered":"Interpol l\u00e8ve la notice rouge visant Paul Watson le d\u00e9fenseur des baleines"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Lev\u00e9e par Interpol mardi de la notice rouge visant \u00e0 l&rsquo;arrestation, sur demande du Japon, du militant \u00e9cologiste am\u00e9ricano-canadien Paul Watson, figure de la d\u00e9fense des baleines, a indiqu\u00e9 \u00e0 l&rsquo;AFP M<sup>e<\/sup> William Juli\u00e9, l&rsquo;un de ses avocats.<\/p>\n<p>\u00ab\u00a0Notice rouge annul\u00e9e\u202f! Les baleiniers japonais ont \u00e9t\u00e9 dans mon dos depuis 14 ans et ma premi\u00e8re arrestation \u00e0 Francfort (Allemagne), en mai 2012\u00a0\u00bb, a salu\u00e9 Paul Watson sur le site internet de sa fondation en faveur des oc\u00e9ans, qui porte son nom.<\/p>\n<p>\u00ab\u00a0\u00c7a a \u00e9t\u00e9 une incroyable traque par une nation tr\u00e8s puissante, utilisant des ressources illimit\u00e9es, mais je suis finalement lib\u00e9r\u00e9 de leur vendetta et de leur pers\u00e9cution incessante\u00a0\u00bb, s&rsquo;est-il encore f\u00e9licit\u00e9.<\/p>\n<p>Un porte-parole d&rsquo;Interpol, l&rsquo;organisation internationale de police criminelle, a confirm\u00e9 \u00e0 l&rsquo;AFP que la commission de contr\u00f4le des fichiers (CCF) avait \u00ab\u00a0d\u00e9cid\u00e9 d&rsquo;effacer\u00a0\u00bb cette notice rouge.<\/p>\n<p>\u00ab\u00a0Ce n&rsquo;est pas un jugement sur le fond du dossier, ou sur ces \u00e9v\u00e9nements qui ont eu lieu en 2010, mais une d\u00e9cision bas\u00e9e sur les r\u00e8gles d&rsquo;Interpol en mati\u00e8re de gestion des donn\u00e9es\u00a0\u00bb, a expliqu\u00e9 ce porte-parole.<\/p>\n<p>\u00ab\u00a0La d\u00e9cision de la CCF a \u00e9t\u00e9 prise \u00e0 la lumi\u00e8re de nouveaux faits, incluant le refus du Danemark d&rsquo;extrader M. Watson\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>Selon des extraits de la d\u00e9cision auxquels l&rsquo;AFP a eu acc\u00e8s, la commission a estim\u00e9 qu&rsquo;une arrestation de M. Watson via cette notice rouge (d&rsquo;abord suspendue en avril) serait \u00ab\u00a0disproportionn\u00e9e\u00a0\u00bb au vu des faits reproch\u00e9s.<\/p>\n<p>Pour la CCF, ce dossier a fait preuve d&rsquo;un \u00ab\u00a0engagement proactif et r\u00e9p\u00e9t\u00e9 des autorit\u00e9s japonaises\u00a0\u00bb, qui \u00ab\u00a0tend \u00e0 mettre en lumi\u00e8re le caract\u00e8re strat\u00e9gique de ce dossier et son importance symbolique\u00a0\u00bb, au-del\u00e0 de son int\u00e9r\u00eat r\u00e9el au fond, ce qui \u00ab\u00a0pourrait d\u00e9montrer l&rsquo;existence d&rsquo;\u00e9l\u00e9ments politiques autour du dossier\u00a0\u00bb.<\/p>\n<h6><strong>\u00ab\u00a0Aspect politique\u00a0\u00bb<\/strong><\/h6>\n<p>Dans un communiqu\u00e9, M<sup>e <\/sup>Juli\u00e9 assure que la CCF a aussi \u00e9voqu\u00e9 dans sa d\u00e9cision \u00ab\u00a0la possible seule implication indirecte de M. Watson (ce qui est contest\u00e9), le temps consid\u00e9rable \u00e9coul\u00e9 depuis les faits all\u00e9gu\u00e9s et le fait que plusieurs autres pays ont refus\u00e9 d&rsquo;agir conform\u00e9ment aux demandes nippones d&rsquo;arrestation ou d&rsquo;extradition\u00a0\u00bb.<\/p>\n<p>M<sup>e<\/sup> Juli\u00e9 s&rsquo;est f\u00e9licit\u00e9 que la CCF souligne \u00ab\u00a0subtilement, mais significativement, l&rsquo;aspect politique du dossier\u00a0\u00bb.<\/p>\n<p>Paul Watson, 74 ans, a \u00e9t\u00e9 d\u00e9tenu au Groenland pendant cinq mois, avant que le Danemark ne rejette une demande d&rsquo;extradition \u00e9manant du Japon, qui l&rsquo;accuse d&rsquo;\u00eatre coresponsable de dommages et blessures \u00e0 bord d&rsquo;un navire baleinier japonais en 2010 dans le cadre d&rsquo;une campagne men\u00e9e par l&rsquo;ONG Sea Shepherd.<\/p>\n<p>Il est \u00e0 noter qu&rsquo;il avait pu rentrer \u00e0 Paris, o\u00f9 il vit depuis 10 ans, le 20 d\u00e9cembre 2024, chaleureusement accueilli par un fan club de militants, mais aussi par de fran\u00e7ais lambda, soutenant l&rsquo;homme, son authenticit\u00e9 et sa r\u00e9silience face \u00e0 l&rsquo;injustice.<\/p>\n<p>Interpol \u00e9met des notices rouges, qui constituent des demandes de localiser une personne suspecte et de proc\u00e9der \u00e0 son arrestation provisoire dans l&rsquo;attente de son extradition, mais celles-ci n&rsquo;ont pas le statut de mandat d&rsquo;arr\u00eat.<\/p>\n<p>\u00ab\u00a0Cette d\u00e9cision met un terme \u00e0 une tentative injustifi\u00e9e de criminalisation, et reconna\u00eet ce que nous avons toujours d\u00e9nonc\u00e9\u00a0: une instrumentalisation de la justice pour prot\u00e9ger les int\u00e9r\u00eats des baleiniers japonais\u00a0\u00bb, a indiqu\u00e9 Sea Shepherd sur X.<\/p>\n<p>\u00ab\u00a0Le mandat d&rsquo;arr\u00eat japonais demeure actif, et tout pays peut encore choisir de l&rsquo;ex\u00e9cuter\u00a0\u00bb, s&rsquo;est toutefois inqui\u00e9t\u00e9e l&rsquo;ONG<\/p>\n<\/div>\n<p><script>(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = \"\/\/connect.facebook.net\/fr_FR\/sdk.js#xfbml=1&version=v2.3\";  fjs.parentNode.insertBefore(js, fjs);}(document, \"script\", \"facebook-jssdk\"));<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.francesoir.fr\/societe-justice\/interpol-leve-la-notice-rouge-visant-le-militant-ecologiste-americano-canadien-paul\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lev\u00e9e par Interpol mardi de la notice rouge visant \u00e0 l&rsquo;arrestation, sur demande du Japon, du militant \u00e9cologiste am\u00e9ricano-canadien Paul Watson, figure de la d\u00e9fense des baleines, a indiqu\u00e9 \u00e0&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12627"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12628"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}