{"id":12691,"date":"2025-07-24T10:18:46","date_gmt":"2025-07-24T08:18:46","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/24\/les-vigies-de-lenvironnement-en-ile-de-france-demissionnent-en-bloc\/"},"modified":"2025-07-24T10:18:46","modified_gmt":"2025-07-24T08:18:46","slug":"les-vigies-de-lenvironnement-en-ile-de-france-demissionnent-en-bloc","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/24\/les-vigies-de-lenvironnement-en-ile-de-france-demissionnent-en-bloc\/","title":{"rendered":"Les vigies de l&#039;environnement en \u00cele-de-France d\u00e9missionnent en bloc"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/afp__20241113__hl_aboureau_2575662__v1__highres__franceparissuburburbanizationurbanc_1_-b6a61.jpg?1753344328\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Les membres de la Mission r\u00e9gionale de l&rsquo;autorit\u00e9 environnementale d&rsquo;\u00cele-de-France ont d\u00e9missionn\u00e9 en bloc. Ils d\u00e9noncent la reprise en main par la pr\u00e9fecture de l&rsquo;instance, qui fournit des avis sur les projets d&rsquo;infrastructures. <br class=\"autobr\" \/> C&rsquo;est une premi\u00e8re et un petit s\u00e9isme dans le monde feutr\u00e9 de l&rsquo;administration environnementale. Lors de leur s\u00e9ance du 16\u00a0juillet, 8 des 9\u00a0membres de la Mission r\u00e9gionale de l&rsquo;autorit\u00e9 environnementale (<span class=\"caps\">MRAE<\/span>) d&rsquo;\u00cele-de-France ont d\u00e9missionn\u00e9. Une instance\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Les-vigies-de-l-environnement-en-Ile-de-France-demissionnent-en-bloc?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Autres-infos\" rel=\"directory\">Info<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Politique\" rel=\"tag\">Politique<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/Les-vigies-de-l-environnement-en-Ile-de-France-demissionnent-en-bloc\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les membres de la Mission r\u00e9gionale de l&rsquo;autorit\u00e9 environnementale d&rsquo;\u00cele-de-France ont d\u00e9missionn\u00e9 en bloc. Ils d\u00e9noncent la reprise en main par la pr\u00e9fecture de l&rsquo;instance, qui fournit des avis sur&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12691","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12691"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12691\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}