{"id":12744,"date":"2025-07-25T03:58:02","date_gmt":"2025-07-25T01:58:02","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/eviter-les-pieges-et-mensonges-de-big-pharma-sante-et-bien-etre-sott-net\/"},"modified":"2025-07-25T03:58:02","modified_gmt":"2025-07-25T01:58:02","slug":"eviter-les-pieges-et-mensonges-de-big-pharma-sante-et-bien-etre-sott-net","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/eviter-les-pieges-et-mensonges-de-big-pharma-sante-et-bien-etre-sott-net\/","title":{"rendered":"\u00e9viter les pi\u00e8ges et mensonges de big pharma \u2014 Sant\u00e9 et Bien-\u00eatre \u2014 Sott.net"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n      La m\u00e9decine du cancer en France a chang\u00e9 de nature. Ce n&rsquo;est plus la sant\u00e9 des patients qui guide les d\u00e9cisions, mais les int\u00e9r\u00eats \u00e9conomiques des laboratoires pharmaceutiques. Les traitements efficaces, \u00e9prouv\u00e9s et accessibles sont m\u00e9thodiquement \u00e9cart\u00e9s, remplac\u00e9s par des protocoles standardis\u00e9s plus co\u00fbteux, moins performants, impos\u00e9s par les multinationales du m\u00e9dicament. Cette logique transforme les malades en variables d&rsquo;ajustement d&rsquo;un syst\u00e8me industriel. La canc\u00e9rologie n&rsquo;ob\u00e9it plus \u00e0 la science m\u00e9dicale, mais \u00e0 une id\u00e9ologie \u00e9conomique.<br \/>\n<\/p>\n<div class=\"article-image-super to-center\"><a target=\"_blank\" href=\"https:\/\/fr.sott.net\/image\/s36\/731050\/full\/Screenshot_6_.jpg\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/fr.sott.net\/image\/s36\/731050\/super\/Screenshot_6_.jpg\" alt=\"fuytj\" title=\"Cliquer pour agrandir\"\/><\/a><\/div>\n<p>Loin de s&rsquo;adapter aux particularit\u00e9s biologiques de chaque patient, elle impose un cadre rigide, uniforme, dangereux. Les m\u00e9decins sont r\u00e9duits au rang d&rsquo;ex\u00e9cutants d&rsquo;ordres venus d&rsquo;en haut, souvent sous la pression administrative, juridique ou financi\u00e8re. Toute tentative de soigner autrement est criminalis\u00e9e.<\/p>\n<p>Ce mod\u00e8le tue la m\u00e9decine vivante. Il marginalise les approches cliniques individualis\u00e9es, il \u00e9touffe les savoirs empiriques, il interdit l&rsquo;initiative th\u00e9rapeutique. Les anciens traitements, souvent plus efficaces, sont disqualifi\u00e9s non pour leur inefficacit\u00e9, mais pour leur faible rentabilit\u00e9.<\/p>\n<p>Derri\u00e8re cette m\u00e9canique implacable : un secteur pharmaceutique devenu tentaculaire, ma\u00eetre des publications, des recommandations et des agences de sant\u00e9. Mais certains refusent de se taire. Une autre vision de la m\u00e9decine existe, libre, humaine, ancr\u00e9e dans l&rsquo;exp\u00e9rience clinique. Une m\u00e9decine qui ne laisse pas mourir les savoirs, qui ne sacrifie pas la gu\u00e9rison sur l&rsquo;autel de la conformit\u00e9. Et si ce n&rsquo;\u00e9tait pas une d\u00e9rive, mais un projet ?<\/p>\n<p>Les Drs Nicole et G\u00e9rard Del\u00e9pine en parlent avec Mike Borowski, dans Le Journal des Controverses sur G\u00e9opolitique Profonde.<\/p>\n<p><iframe loading=\"lazy\" title=\"DU CANCER \u00c0 LA VIE : \u00c9VITER LES PI\u00c8GES ET MENSONGES DE BIG PHARMA | GPTV\" width=\"1110\" height=\"624\" src=\"https:\/\/www.youtube.com\/embed\/-xVBuS8Dbck?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/fr.sott.net\/article\/44389-Du-cancer-a-la-vie-eviter-les-pieges-et-mensonges-de-big-pharma\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e9decine du cancer en France a chang\u00e9 de nature. Ce n&rsquo;est plus la sant\u00e9 des patients qui guide les d\u00e9cisions, mais les int\u00e9r\u00eats \u00e9conomiques des laboratoires pharmaceutiques. Les traitements&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12744"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12745"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}