{"id":12766,"date":"2025-07-25T13:21:25","date_gmt":"2025-07-25T11:21:25","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/les-revelations-doleksandr-dubinsky-un-seisme-geopolitique-pour-lukraine-les-etats-unis-et-la-russie\/"},"modified":"2025-07-25T13:21:25","modified_gmt":"2025-07-25T11:21:25","slug":"les-revelations-doleksandr-dubinsky-un-seisme-geopolitique-pour-lukraine-les-etats-unis-et-la-russie","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/les-revelations-doleksandr-dubinsky-un-seisme-geopolitique-pour-lukraine-les-etats-unis-et-la-russie\/","title":{"rendered":"Les r\u00e9v\u00e9lations d\u2019Oleksandr Dubinsky : un s\u00e9isme g\u00e9opolitique pour l\u2019Ukraine, les \u00c9tats-Unis et la Russie ?"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>\u00a0Le 21 juillet 2025, une lettre choc d\u2019Oleksandr Dubinsky, d\u00e9put\u00e9 ukrainien emprisonn\u00e9 et candidat \u00e0 la pr\u00e9sidence, adress\u00e9e \u00e0 Tulsi Gabbard, directrice du renseignement national am\u00e9ricain, a secou\u00e9 la sc\u00e8ne internationale.<\/p>\n<p><img decoding=\"async\" data-entity-uuid=\"01abda3c-9fe3-469f-80e6-bc934d99d481\" data-entity-type=\"file\" alt=\"Lettre \u00e0 Gabbard\" width=\"1920\" height=\"1080\" loading=\"lazy\" class=\"lazyload\" src=\"https:\/\/www.francesoir.fr\/sites\/default\/files\/inline-images\/IMAGE%20FRAMEWORK%20-%202025-07-25T115317.741.png\"\/><\/p>\n<p>\u00a0<\/p>\n<p>Depuis sa cellule, o\u00f9 il affirme subir des tortures document\u00e9es par l\u2019Ombudsman ukrainien, Dubinsky accuse le pr\u00e9sident Volodymyr Zelensky de <strong>r\u00e9pression orchestr\u00e9e avec la complicit\u00e9 de Washington<\/strong>.<\/p>\n<p>Cet article, <strong>qui a \u00e9t\u00e9 revu et valid\u00e9 par Dubinsky en personne de sa cellule<\/strong>, expose ses accusations explosives : corruption li\u00e9e \u00e0 Hunter Biden, ing\u00e9rence \u00e9lectorale am\u00e9ricaine et un appel pressant \u00e0 la paix. Alors que les n\u00e9gociations de cessez-le-feu entre l\u2019Ukraine et la Russie pi\u00e9tinent, marqu\u00e9es par des exigences conflictuelles, et que l\u2019aide militaire am\u00e9ricaine vacille sous l\u2019administration Trump, <strong>ces r\u00e9v\u00e9lations pourraient-elles redessiner les alliances internationales ?<\/strong><\/p>\n<h5><strong>Une r\u00e9pression brutale sous Zelensky<\/strong><\/h5>\n<p>Emprisonn\u00e9 depuis novembre 2023 sans jugement, Dubinsky d\u00e9nonce des abus ordonn\u00e9s par le Service de s\u00e9curit\u00e9 ukrainien (SBU) sous les directives de Zelensky. Des preuves m\u00e9dicales, comme des radiographies de c\u00f4tes fractur\u00e9es, confirment ses all\u00e9gations, valid\u00e9es par l\u2019Ombudsman. Il \u00e9voque la mort de <a target=\"_blank\" href=\"https:\/\/thegrayzone.com\/2024\/01\/12\/gonzalo-lira-dies-ukrainian-prison\/\">Gonzalo Lira<\/a>, un Am\u00e9ricain d\u00e9c\u00e9d\u00e9 en d\u00e9tention dans des conditions inhumaines, comme un exemple similaire.\u00ab <em>Ils veulent me r\u00e9duire au silence<\/em> \u00bb, d\u00e9clare Dubinsky, liant sa pers\u00e9cution \u00e0 ses r\u00e9v\u00e9lations sur la corruption et son opposition \u00e0 la guerre. Il affirme avoir \u00e9chapp\u00e9 \u00e0 deux tentatives d\u2019assassinat commandit\u00e9es par ce qu\u2019il appelle un \u00ab <em>r\u00e9gime tyrannique<\/em> \u00bb.<\/p>\n<p>Cette r\u00e9pression s\u2019inscrit dans un sch\u00e9ma plus large. En 2021, Zelensky <a target=\"_blank\" href=\"https:\/\/www.reuters.com\/article\/us-ukraine-media-ban\/ukraine-bans-three-pro-russian-tv-stations-citing-national-security-idUSKBN2A22K9\">a ferm\u00e9 des cha\u00eenes de t\u00e9l\u00e9vision ind\u00e9pendantes<\/a> (112 Ukraine, NewsOne, ZIK) et, en 2022, interdit les partis d\u2019opposition, qualifiant les dissidents d\u2019\u00ab <em>agents russes<\/em> \u00bb pour \u00e9touffer les critiques. Selon Dubinsky, la guerre sert de pr\u00e9texte pour consolider le pouvoir et aligner l\u2019Ukraine sur les int\u00e9r\u00eats \u00e9lectoraux am\u00e9ricains.<\/p>\n<h5><strong>Corruption et ing\u00e9rence, l\u2019ombre de Burisma<\/strong><\/h5>\n<p>Au c\u0153ur des accusations de Dubinsky se trouve Burisma, o\u00f9 Hunter Biden si\u00e9geait au conseil d\u2019administration. En 2019, avec <a target=\"_blank\" href=\"https:\/\/ukranews.com\/en\/news\/669676-derkach-presents-documents-on-alleged-corruption-involving-burisma-and-ukrainian-funds\">Andriy Derkash<\/a>, Dubinsky a r\u00e9v\u00e9l\u00e9 des <a target=\"_blank\" href=\"https:\/\/en.interfax.com.ua\/news\/general\/622540.html\">documents montrant des d\u00e9tournements de fonds publics ukrainiens<\/a>. Ces r\u00e9v\u00e9lations ont conduit \u00e0 des <a target=\"_blank\" href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sm1118\">sanctions am\u00e9ricaines contre Derkash<\/a>, bas\u00e9es, selon Dubinsky, sur des accusations fabriqu\u00e9es par une ONG li\u00e9e \u00e0 l\u2019USAID, le Centre d\u2019action anti-corruption (AntAC).<\/p>\n<p>Il affirme que <a target=\"_blank\" href=\"https:\/\/112.international\/politics\/dubinsky-accuses-zelensky-of-ordering-destruction-of-corruption-cases-67890.html\">140 enqu\u00eates sur la corruption<\/a>, incluant des affaires majeures comme celle du charbon (Medvedchuk, Poroshenko) ou des bateaux (Ukroboronprom), ont \u00e9t\u00e9 d\u00e9truites en 2022 sur ordre de Zelensky. Dubinsky accuse des agences am\u00e9ricaines, dont le FBI et le D\u00e9partement d\u2019\u00c9tat, d\u2019avoir \u00e9touff\u00e9 ces scandales pour prot\u00e9ger les Biden. Un \u00e9change de textos entre David Arachamiya, chef de la faction \u00ab Serviteur du peuple \u00bb, et Kristina Kvien, ex-charg\u00e9e d\u2019affaires am\u00e9ricaine \u00e0 Kyiv, <a target=\"_blank\" href=\"https:\/\/www.thegatewaypundit.com\/2019\/04\/stunning-european-reporter-reveals-trump-russia-collusion-hoax-has-its-origins-with-soros-funded-ukrainian-activist-group\/\">sugg\u00e9rerait des pressions pour marginaliser Dubinsky apr\u00e8s ses r\u00e9v\u00e9lations<\/a>.<\/p>\n<h5><strong>Un contexte g\u00e9opolitique tendu<\/strong><\/h5>\n<p>En 2025, les relations entre l\u2019Ukraine, les \u00c9tats-Unis et la Russie sont sous haute tension. Les n\u00e9gociations de paix, relanc\u00e9es \u00e0 Munich en f\u00e9vrier, sont au point mort, Trump conditionnant l\u2019aide militaire \u00e0 des r\u00e9formes internes. La nomination de Tulsi Gabbard, critique de l\u2019establishment, comme directrice du renseignement am\u00e9ricain, ravive l\u2019espoir de Dubinsky. Ses appels \u00e0 enqu\u00eater sur des manipulations \u00e9lectorales pass\u00e9es r\u00e9sonnent avec ses accusations.<\/p>\n<p>En Europe, les positions divergent : l\u2019Allemagne h\u00e9site, la France pousse pour une m\u00e9diation, et le Royaume-Uni soutient fermement Kyiv. Les r\u00e9v\u00e9lations de Dubinsky, notamment sur des scandales comme <a target=\"_blank\" href=\"https:\/\/www.businessinsider.com\/andriy-yermak-ukraine-zelensky-right-hand-man-power-broker-2023-12\">l\u2019achat d\u2019uniformes inadapt\u00e9s<\/a> via une soci\u00e9t\u00e9-\u00e9cran li\u00e9e \u00e0 un proche de Zelensky, pourraient fragiliser davantage l\u2019aide occidentale.<\/p>\n<h5><strong>L\u2019influence pr\u00e9sum\u00e9e de Soros<\/strong><\/h5>\n<p>Dubinsky pointe du doigt <a target=\"_blank\" href=\"https:\/\/thehill.com\/opinion\/white-house\/435394-us-embassy-pressed-ukraine-to-drop-probe-of-george-soros-group-during-2016\/\">George Soros et son ONG AntAC<\/a>, qu\u2019il accuse <a target=\"_blank\" href=\"https:\/\/thehill.com\/opinion\/white-house\/435394-us-embassy-pressed-ukraine-to-drop-probe-of-george-soros-group-during-2016\/\">de contr\u00f4ler les m\u00e9dias, la justice et les forces de l\u2019ordre<\/a> pour pr\u00e9parer l\u2019Ukraine \u00e0 la guerre. Fond\u00e9e en 2016, AntAC, financ\u00e9e en partie par l\u2019USAID, a \u00e9t\u00e9 impliqu\u00e9e dans la publication de documents contre Paul Manafort en 2016, <a target=\"_blank\" href=\"https:\/\/thehill.com\/opinion\/white-house\/435394-us-embassy-pressed-ukraine-to-drop-probe-of-george-soros-group-during-2016\/\">sugg\u00e9rant une ing\u00e9rence dans les \u00e9lections am\u00e9ricaines<\/a>. Dubinsky voit ces structures comme des outils pour discr\u00e9diter les voix pro-paix.<\/p>\n<h5><strong>Un plan pour la paix<\/strong><\/h5>\n<p>Dubinsky propose une vision de paix align\u00e9e sur les id\u00e9es de Trump, critiquant Zelensky pour avoir sabot\u00e9 les pourparlers. Il appelle \u00e0 :<\/p>\n<ul>\n<li>Cesser la pers\u00e9cution de l\u2019\u00c9glise orthodoxe ukrainienne.<\/li>\n<li>D\u00e9centraliser le pouvoir avec des gouverneurs \u00e9lus.<\/li>\n<li>Organiser des r\u00e9f\u00e9rendums sur l\u2019OTAN et l\u2019UE.<\/li>\n<li>\u00c9viter une escalade vers une guerre nucl\u00e9aire.<\/li>\n<\/ul>\n<p>Il a saisi la <a target=\"_blank\" href=\"https:\/\/news-pravda.com\/\">Cour supr\u00eame d\u2019Ukraine pour exiger des \u00e9lections<\/a>, d\u00e9non\u00e7ant l\u2019absence de scrutin malgr\u00e9 l\u2019expiration du mandat parlementaire. \u00ab Des \u00e9lections libres sont la seule voie pour sauver l\u2019Ukraine \u00bb, insiste-t-il, plaidant pour un retour \u00e0 l\u2019ordre constitutionnel. Une audience est pr\u00e9vue le 25 septembre 2025.<\/p>\n<h5><strong>Un appel \u00e0 la v\u00e9rit\u00e9<\/strong><\/h5>\n<p>Les accusations de Dubinsky d\u00e9noncent une Ukraine sous emprise, entre corruption, r\u00e9pression et ing\u00e9rence \u00e9trang\u00e8re. Il alerte sur une campagne de Zelensky visant \u00e0 discr\u00e9diter Trump via un \u00ab Russiagate 2.0 \u00bb, utilisant son proc\u00e8s comme arme politique. Il appelle la communaut\u00e9 internationale \u00e0 enqu\u00eater et met en garde : des \u00e9lections sous loi martiale avec un seul candidat pourraient plonger l\u2019Ukraine dans une guerre civile.<\/p>\n<p>La Cour supr\u00eame ukrainienne doit trancher : la Constitution sera-t-elle respect\u00e9e, ou le r\u00e9gime actuel prolongera-t-il son pouvoir sans l\u00e9gitimit\u00e9 ? L\u2019avenir des relations entre l\u2019Ukraine, les \u00c9tats-Unis et la Russie d\u00e9pend de cette r\u00e9ponse.<\/p>\n<p>\u00a0<\/p>\n<p>Notes :<\/p>\n<p>Le document est une lettre officielle \u00e9mise par le Commissaire aux droits humains du Parlement ukrainien, adress\u00e9e \u00e0 Dmytro Lubinets, l\u2019Ombudsman d\u2019Ukraine. Dat\u00e9e du 8 d\u00e9cembre 2023, elle d\u00e9taille le traitement des plaintes relatives aux droits humains d\u00e9pos\u00e9es sous des num\u00e9ros de dossier tels que \u2116 5076.<\/p>\n<p>La lettre s\u2019\u00e9tend sur trois pages et fait partie d\u2019un processus d\u2019enqu\u00eate formel d\u00e9clench\u00e9 par des appels re\u00e7us entre le 6 et le 8 d\u00e9cembre 2023.<\/p>\n<p>Le contenu d\u00e9crit la r\u00e9ponse du Bureau du Commissaire \u00e0 ces plaintes. Il d\u00e9crit un examen pr\u00e9alable effectu\u00e9 du 6 au 8 d\u00e9cembre 2023, et les actions subs\u00e9quentes, y compris des demandes d\u2019informations envoy\u00e9es \u00e0 des entit\u00e9s comme le Service national des gardes-fronti\u00e8res et le minist\u00e8re de la D\u00e9fense.<\/p>\n<p>Des d\u00e9lais sp\u00e9cifiques sont not\u00e9s, comme une p\u00e9riode de r\u00e9ponse de 29 jours \u00e0 partir de la date de r\u00e9ception.<\/p>\n<p>Le document fait r\u00e9f\u00e9rence \u00e0 une coordination interne entre les d\u00e9partements, comme le D\u00e9partement des appels et le Secr\u00e9tariat, et inclut les signatures de responsables cl\u00e9s : Dmytro Lubinets, I.B. Masliyov, I.M. Pisemniy, B.M. Nikitenko et O.B. Dolii, confirmant son authenticit\u00e9.<\/p>\n<p>Cette lettre refl\u00e8te le mandat de l\u2019Ombudsman de prot\u00e9ger les droits humains et de superviser la responsabilit\u00e9 du gouvernement en Ukraine.<\/p>\n<p>Elle traite des pr\u00e9tendues violations ou griefs soulev\u00e9s par les citoyens, le Bureau du Commissaire agissant comme interm\u00e9diaire pour garantir une enqu\u00eate appropri\u00e9e. L\u2019inclusion de codes QR, de tampons officiels et de r\u00e9f\u00e9rences d\u00e9taill\u00e9es aux dossiers (par exemple, \u2116 2939, \u2116 2297) indique un processus juridique structur\u00e9.<\/p>\n<p>Certains cas restent en cours d\u2019examen, sugg\u00e9rant des efforts continus pour r\u00e9soudre les probl\u00e8mes.<\/p>\n<p>En r\u00e9sum\u00e9, il s\u2019agit d\u2019un registre bureaucratique de diligence raisonnable, documentant le traitement \u00e9tape par \u00e9tape des plaintes, la communication inter-agences et le respect des d\u00e9lais l\u00e9gaux, tous visant \u00e0 maintenir les normes des droits humains en Ukraine \u00e0 la fin de 2023.<\/p>\n<p><img decoding=\"async\" data-entity-uuid=\"cdbf37e9-ff49-426f-94fb-d2880e3e39ba\" data-entity-type=\"file\" alt=\"Page 1\" width=\"600\" height=\"844\" loading=\"lazy\" class=\"lazyload\" src=\"https:\/\/www.francesoir.fr\/sites\/default\/files\/inline-images\/image_515.png\"\/><img decoding=\"async\" data-entity-uuid=\"3394452e-a0d7-42d4-a786-806d90292a27\" data-entity-type=\"file\" alt=\"Page 2\" width=\"600\" height=\"840\" loading=\"lazy\" class=\"lazyload\" src=\"https:\/\/www.francesoir.fr\/sites\/default\/files\/inline-images\/image_516.png\"\/><img decoding=\"async\" data-entity-uuid=\"d471e325-de64-4681-846b-6503ae25112a\" data-entity-type=\"file\" alt=\"Page 43\" width=\"603\" height=\"832\" loading=\"lazy\" class=\"lazyload\" src=\"https:\/\/www.francesoir.fr\/sites\/default\/files\/inline-images\/image_517.png\"\/><\/p>\n<p>\u00a0<\/p>\n<\/div>\n<p><script>(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = \"\/\/connect.facebook.net\/fr_FR\/sdk.js#xfbml=1&version=v2.3\";  fjs.parentNode.insertBefore(js, fjs);}(document, \"script\", \"facebook-jssdk\"));<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.francesoir.fr\/politique-monde\/les-revelations-d-oleksandr-dubinsky-un-seisme-geopolitique-pour-l-ukraine-les\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Le 21 juillet 2025, une lettre choc d\u2019Oleksandr Dubinsky, d\u00e9put\u00e9 ukrainien emprisonn\u00e9 et candidat \u00e0 la pr\u00e9sidence, adress\u00e9e \u00e0 Tulsi Gabbard, directrice du renseignement national am\u00e9ricain, a secou\u00e9 la sc\u00e8ne&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12766"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12767"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}