{"id":12770,"date":"2025-07-25T14:28:12","date_gmt":"2025-07-25T12:28:12","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/meta-tourne-le-dos-aux-publicites-politiques-en-europe-rt-en-francais\/"},"modified":"2025-07-25T14:28:12","modified_gmt":"2025-07-25T12:28:12","slug":"meta-tourne-le-dos-aux-publicites-politiques-en-europe-rt-en-francais","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/25\/meta-tourne-le-dos-aux-publicites-politiques-en-europe-rt-en-francais\/","title":{"rendered":"Meta tourne le dos aux publicit\u00e9s politiques en Europe \u2014 RT en fran\u00e7ais"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/mf.b37mrtl.ru\/french\/images\/2025.07\/thumbnail\/688373a787f3ec10164f4947.jpg\" \/><\/p>\n<div>\n<p class=\"text__summary\">\n                                        Face aux nouvelles obligations europ\u00e9ennes jug\u00e9es trop complexes et juridiquement floues, Meta annonce la fin des publicit\u00e9s politiques sur Facebook et Instagram dans l\u2019UE d\u00e8s octobre. L\u2019entreprise invoque des difficult\u00e9s op\u00e9rationnelles majeures li\u00e9es aux exigences de transparence impos\u00e9es par Bruxelles.\n                                    <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/francais.rt.com\/news\/123413-meta-tourne-dos-publicites-politiques-en-europe\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Face aux nouvelles obligations europ\u00e9ennes jug\u00e9es trop complexes et juridiquement floues, Meta annonce la fin des publicit\u00e9s politiques sur Facebook et Instagram dans l\u2019UE d\u00e8s octobre. L\u2019entreprise invoque des difficult\u00e9s&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12770"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12771"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}