{"id":12845,"date":"2025-07-26T19:05:59","date_gmt":"2025-07-26T17:05:59","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/26\/des-dizaines-de-milliers-de-personnes-protestent-contre-le-pouvoir-pro-europeen-de-maia-sandu-rt-en-francais\/"},"modified":"2025-07-26T19:05:59","modified_gmt":"2025-07-26T17:05:59","slug":"des-dizaines-de-milliers-de-personnes-protestent-contre-le-pouvoir-pro-europeen-de-maia-sandu-rt-en-francais","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/26\/des-dizaines-de-milliers-de-personnes-protestent-contre-le-pouvoir-pro-europeen-de-maia-sandu-rt-en-francais\/","title":{"rendered":"des dizaines de milliers de personnes protestent contre le pouvoir pro-europ\u00e9en de Maia Sandu\u202f \u2014 RT en fran\u00e7ais"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/mf.b37mrtl.ru\/french\/images\/2025.07\/thumbnail\/6885047e87f3ec69f97e2626.jpg\" \/><\/p>\n<div>\n<p class=\"text__summary\">\n                                        \u00c0 deux mois des \u00e9lections l\u00e9gislatives, la capitale moldave a \u00e9t\u00e9 le th\u00e9\u00e2tre d\u2019une immense manifestation dirig\u00e9e par un nouveau bloc d\u2019opposition pr\u00f4nant le r\u00e9tablissement des liens avec la Russie. Les manifestants d\u00e9noncent la r\u00e9pression du pouvoir et les d\u00e9rives autoritaires de la pr\u00e9sidente Maia Sandu.\n                                    <\/p>\n<p>Des dizaines de milliers de citoyens sont descendus dans les rues de Chisinau ce 26 juillet pour participer \u00e0 une manifestation massive contre la politique men\u00e9e par la pr\u00e9sidente moldave Maia Sandu et son parti pro-europ\u00e9en, \u00ab\u202fAction et solidarit\u00e9\u202f\u00bb (PAS), au pouvoir. L\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 par un nouveau bloc d\u2019opposition compos\u00e9 de quatre partis de gauche\u202f: le Parti des socialistes de la R\u00e9publique de Moldavie (PCRM), le Parti des communistes, \u00ab\u202fC\u0153ur de la Moldavie\u202f\u00bb et \u00ab\u202fL\u2019Avenir de la Moldavie\u202f\u00bb. Parmi les figures pr\u00e9sentes, on retrouve les anciens pr\u00e9sidents Igor Dodon et Vladimir Voronine, l\u2019ex-Premier ministre Vasile Tarlev ainsi que l\u2019ancienne gouverneure de Gagaouzie, Irina Vlah.<\/p>\n<p>Le cort\u00e8ge, arborant drapeaux nationaux et \u00e9tendards des partis, a converg\u00e9 vers le centre de la ville en scandant des slogans tels que \u00ab\u202fPour une Moldavie souveraine\u202f\u00bb, \u00ab\u202fEn unit\u00e9, notre force\u202f\u00bb, \u00ab\u202fLa Moldavie a un avenir\u202f\u00bb ou encore \u00ab\u202fPour la neutralit\u00e9 de la Moldavie\u202f\u00bb.<\/p>\n<h2><strong>Blocage policier et climat de r\u00e9pression<\/strong><\/h2>\n<p>Malgr\u00e9 la chaleur extr\u00eame, les organisateurs estiment que plusieurs dizaines de milliers de manifestants \u00e9taient pr\u00e9sents. Selon Vlad Batrincea, d\u00e9put\u00e9 du Bloc des communistes et socialistes, plus de la moiti\u00e9 des citoyens souhaitant participer ont \u00e9t\u00e9 emp\u00each\u00e9s de rejoindre la capitale en raison des barrages policiers install\u00e9s sur ordre du gouvernement.<\/p>\n<p>\u00ab\u202fLe pouvoir a peur de la voix du peuple. Il utilise des m\u00e9thodes dictatoriales pour \u00e9touffer la contestation\u202f\u00bb, a d\u00e9nonc\u00e9 Igor Dodon. Il a accus\u00e9 la police d\u2019avoir d\u00e9lib\u00e9r\u00e9ment bloqu\u00e9 les routes et retenu les bus transportant des manifestants. D\u2019apr\u00e8s les d\u00e9clarations de l\u2019opposition, certains participants ont m\u00eame \u00e9t\u00e9 arr\u00eat\u00e9s ou contr\u00f4l\u00e9s arbitrairement en route.<\/p>\n<p>Depuis plusieurs ann\u00e9es, le gouvernement de Maia Sandu est accus\u00e9 par ses opposants d\u2019avoir instaur\u00e9 une r\u00e9pression syst\u00e9matique. De nombreux m\u00e9dias ind\u00e9pendants ont \u00e9t\u00e9 bloqu\u00e9s et plusieurs hommes politiques ont \u00e9t\u00e9 poursuivis sous divers pr\u00e9textes pour avoir d\u00e9fendu des positions amicales \u00e0 la Russie. La surveillance polici\u00e8re, les poursuites judiciaires et la fermeture des espaces d\u2019expression sont devenues des pratiques fr\u00e9quentes.<\/p>\n<h2><strong>Vers une alternative politique neutre<\/strong>\u00a0<\/h2>\n<p>Le bloc d\u2019opposition en formation, qui n\u2019a pas encore de nom officiel, se pr\u00e9pare \u00e0 se pr\u00e9senter ensemble aux \u00e9lections parlementaires du 28 septembre. Ce regroupement revendique le r\u00e9tablissement des relations avec la Russie et rejette l\u2019orientation pro-OTAN et pro-UE de l\u2019actuel pouvoir. Irina Vlah a d\u00e9clar\u00e9 lors du rassemblement\u00a0: \u00ab\u202fNotre objectif n\u2019est pas seulement de battre le PAS, mais de lib\u00e9rer le pays de ce r\u00e9gime.\u202f\u00bb Elle a ajout\u00e9 que la Moldavie \u00ab\u202fne sera jamais un outil de guerre pour l\u2019Occident\u202f\u00bb et a d\u00e9nonc\u00e9 \u00ab\u202fl\u2019utilisation de la police et de la diaspora \u00e0 l\u2019\u00e9tranger, notamment en Roumanie, pour manipuler les r\u00e9sultats \u00e9lectoraux\u202f\u00bb.<\/p>\n<p>Les sondages indiquent que le PAS pourrait obtenir 39,2\u00a0% des voix, mais il ne serait pas en mesure de gouverner seul. L\u2019opposition d\u00e9clare voir dans ces \u00e9lections une opportunit\u00e9 de sauver la Moldavie \u00ab de la guerre\u202f\u00bb.<\/p>\n<p>\u00ab\u202fAujourd\u2019hui, nous vivons dans une guerre id\u00e9ologique\u202f\u00bb, a r\u00e9sum\u00e9 le d\u00e9put\u00e9 Constantin Staris, avant d\u2019ajouter\u00a0: \u00ab\u202fNos dirigeants ont vendu la souverainet\u00e9 du pays \u00e0 Bruxelles et Washington.\u202f\u00bb La mobilisation de Chisinau marque ainsi une \u00e9tape d\u00e9cisive dans la lutte pour le retour \u00e0 une Moldavie souveraine, pacifique et respectueuse de son histoire.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/francais.rt.com\/international\/123449-moldavie-dizaines-milliers-personnes-protestent-contre-pouvoir-pro-europeen-de-maia-sandu\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 deux mois des \u00e9lections l\u00e9gislatives, la capitale moldave a \u00e9t\u00e9 le th\u00e9\u00e2tre d\u2019une immense manifestation dirig\u00e9e par un nouveau bloc d\u2019opposition pr\u00f4nant le r\u00e9tablissement des liens avec la Russie.&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12845"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12846"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}