{"id":12847,"date":"2025-07-26T19:38:38","date_gmt":"2025-07-26T17:38:38","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/26\/aucun-signe-dapaisement-au-troisieme-jour-de-conflit-entre-le-cambodge-et-la-thailande\/"},"modified":"2025-07-26T19:38:38","modified_gmt":"2025-07-26T17:38:38","slug":"aucun-signe-dapaisement-au-troisieme-jour-de-conflit-entre-le-cambodge-et-la-thailande","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/26\/aucun-signe-dapaisement-au-troisieme-jour-de-conflit-entre-le-cambodge-et-la-thailande\/","title":{"rendered":"Aucun signe d\u2019apaisement au troisi\u00e8me jour de conflit entre le Cambodge et la Tha\u00eflande"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"gateaux-secs__text\">\n                        Les cookies et technologies similaires que nous utilisons sur Mediapart sont de diff\u00e9rentes natures et nous permettent de poursuivre diff\u00e9rentes finalit\u00e9s. <\/p>\n<p>Certains sont n\u00e9cessaires au fonctionnement du site et de l\u2019application mobile (vous ne pouvez pas les refuser). D\u2019autres sont optionnels mais contribuent \u00e0 faciliter votre exp\u00e9rience de lecteur ou de lectrice et d\u2019une certaine fa\u00e7on \u00e0 soutenir Mediapart. Vous pouvez les refuser ou les accepter ci-dessous, selon leurs finalit\u00e9s. <\/p>\n<p><b>Acceptez-vous que Mediapart utilise des cookies ou technologies similaires pour les finalit\u00e9s suivantes\u00a0?<\/b> <\/p>\n<p>Vous pouvez faire votre choix, pour chaque cat\u00e9gorie, en activant ou d\u00e9sactivant le bouton interrupteur.\n                    <\/p>\n<div class=\"gateaux-secs__settings-body-content-block\">\n<div class=\"gateaux-secs__settings-body-content-block-heading\">\n<p class=\"gateaux-secs__text\"><b>N\u00e9cessaires au fonctionnement<br \/>du site ou de l\u2019application<\/b><\/p>\n<\/p><\/div>\n<p class=\"gateaux-secs__text\">Connexion des abonn\u00e9\u00b7es, mesure d\u2019audience anonymis\u00e9e, envoi des notifications push, suivi des pannes, mise en avant de nos services\u00a0: ces outils sont n\u00e9cessaires au suivi de l\u2019activit\u00e9 de nos services et \u00e0 leur bon fonctionnement.<\/p>\n<p>                                                            <button aria-expanded=\"false\" class=\"gateaux-secs__details-trigger focus\"><br \/>\n                                    en savoir plus<br \/>\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"icon\" viewbox=\"0 0 32 32\" aria-hidden=\"true\" focusable=\"false\">\n                                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.2929 25.7071C10.9024 25.3166 10.9024 24.6834 11.2929 24.2929L19.5858 16L11.2929 7.70711C10.9024 7.31658 10.9024 6.68342 11.2929 6.29289C11.6834 5.90237 12.3166 5.90237 12.7071 6.29289L21.7071 15.2929C22.0976 15.6834 22.0976 16.3166 21.7071 16.7071L12.7071 25.7071C12.3166 26.0976 11.6834 26.0976 11.2929 25.7071Z\"\/>\n                                    <\/svg><br \/>\n                                <\/button><\/p>\n<div class=\"gateaux-secs__details\" hidden=\"\">\n<p class=\"gateaux-secs__text\">Voici les diff\u00e9rents cookies et technologies similaires compris dans cette cat\u00e9gorie\u00a0:<\/p>\n<ul class=\"gateaux-secs__text\">\n<li><b>Cookies d\u2019authentification<\/b>\u00a0: connexion des abonn\u00e9\u00b7es.<\/li>\n<li><b>AT Internet<\/b>\u00a0: mesure d\u2019audience anonymis\u00e9e<\/li>\n<li><b>Affichage de contenus \u00e9ditoriaux multim\u00e9dias<\/b>\u00a0: vid\u00e9os (YouTube, Dailymotion, Vimeo, INA), r\u00e9seaux sociaux (Facebook, Instagram, Pinterest, Twitter), documents (Scribd, Document Cloud, Slideshare), sons (SoundCloud, Spotify, Deezer), cartes (Google Maps, Mapbox, CartoDB, uMap), infographies (Highcharts, GitHub, Datawrapper, Flourish, Infogram, ThingLink, jQuery, Google Fonts, Bootstrap), live blogs (24liveblog, CoverItLive), aide \u00e0 l\u2019int\u00e9gration de m\u00e9dia dans les publications Journal et Club (Embedly).<\/li>\n<li><b>Typeform<\/b>\u00a0: questionnaires facultatifs pour recueillir les avis des lecteurs sur nos produits num\u00e9riques.<\/li>\n<li><b>Datadog (uniquement sur le site web)<\/b>\u00a0: indicateurs techniques et \u00e9quilibrage de charge.<\/li>\n<li><b>Selligent (uniquement sur le site web)<\/b>\u00a0: communication avec l\u2019abonn\u00e9\u00b7e, mise en avant des services, offres et avantages.<\/li>\n<li><b>Batch (uniquement sur l\u2019application)<\/b>\u00a0: envoi de notifications push et de messages in-app.<\/li>\n<li><b>Firebase Cloud Messaging (uniquement sur l\u2019application)<\/b>\u00a0: n\u00e9cessaire au fonctionnement des notifications push sur Android.<\/li>\n<li><b>Microsoft App Center (uniquement sur l\u2019application)<\/b>\u00a0: syst\u00e8me de mise \u00e0 jour et de suivi des pannes de l\u2019application.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<div class=\"gateaux-secs__settings-body-content-block\">\n<p class=\"gateaux-secs__text\">Ces outils nous permettent de recueillir des statistiques de fr\u00e9quentation du site et de l\u2019application mobile pour comprendre les usages, d\u00e9tecter d\u2019\u00e9ventuels probl\u00e8mes et optimiser l\u2019ergonomie de nos produits.<\/p>\n<p>                                                            <button aria-expanded=\"false\" class=\"gateaux-secs__details-trigger focus\"><br \/>\n                                    en savoir plus<br \/>\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"icon\" viewbox=\"0 0 32 32\" aria-hidden=\"true\" focusable=\"false\">\n                                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.2929 25.7071C10.9024 25.3166 10.9024 24.6834 11.2929 24.2929L19.5858 16L11.2929 7.70711C10.9024 7.31658 10.9024 6.68342 11.2929 6.29289C11.6834 5.90237 12.3166 5.90237 12.7071 6.29289L21.7071 15.2929C22.0976 15.6834 22.0976 16.3166 21.7071 16.7071L12.7071 25.7071C12.3166 26.0976 11.6834 26.0976 11.2929 25.7071Z\"\/>\n                                    <\/svg><br \/>\n                                <\/button><\/p>\n<div class=\"gateaux-secs__details\" hidden=\"\">\n<p class=\"gateaux-secs__text\">Voici les outils tiers compris dans cette cat\u00e9gorie\u00a0:<\/p>\n<ul class=\"gateaux-secs__text\">\n<li><b>AT Internet<\/b>\u00a0: mesure d\u2019audience reli\u00e9e \u00e0 l\u2019identifiant d\u2019abonn\u00e9\u00b7e.<\/li>\n<li><b>CrazyEggs (uniquement sur le site web)<\/b>\u00a0: analyse de parcours client.<\/li>\n<li><b>Nonli (uniquement sur le site web)<\/b>\u00a0: permet \u00e0 notre \u00e9quipe des r\u00e9seaux sociaux de publier les contenus Mediapart sur les r\u00e9seaux sociaux.<\/li>\n<li><b>Qiota (uniquement sur le site web)<\/b>\u00a0: gestion du syst\u00e8me de datawall.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<div class=\"gateaux-secs__settings-body-content-block\">\n<p class=\"gateaux-secs__text\">Il n\u2019y a pas de publicit\u00e9 sur Mediapart. Mais nous faisons la promotion de nos contenus et services sur d\u2019autres sites et r\u00e9seaux sociaux. Pour cela, nous utilisons les technologies mises \u00e0 disposition par certains acteurs publicitaires.<\/p>\n<p>                                                            <button aria-expanded=\"false\" class=\"gateaux-secs__details-trigger focus\"><br \/>\n                                    en savoir plus<br \/>\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"icon\" viewbox=\"0 0 32 32\" aria-hidden=\"true\" focusable=\"false\">\n                                        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.2929 25.7071C10.9024 25.3166 10.9024 24.6834 11.2929 24.2929L19.5858 16L11.2929 7.70711C10.9024 7.31658 10.9024 6.68342 11.2929 6.29289C11.6834 5.90237 12.3166 5.90237 12.7071 6.29289L21.7071 15.2929C22.0976 15.6834 22.0976 16.3166 21.7071 16.7071L12.7071 25.7071C12.3166 26.0976 11.6834 26.0976 11.2929 25.7071Z\"\/>\n                                    <\/svg><br \/>\n                                <\/button><\/p>\n<div class=\"gateaux-secs__details\" hidden=\"\">\n<p class=\"gateaux-secs__text\">Voici les outils tiers compris dans cette cat\u00e9gorie\u00a0:<\/p>\n<ul class=\"gateaux-secs__text\">\n<li><b>Facebook (uniquement sur le site web)<\/b>\u00a0: ciblage d\u2019audience sur les r\u00e9seaux sociaux pour faire la promotion de Mediapart.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<div class=\"gateaux-secs__settings-body-content-block\">\n<div class=\"gateaux-secs__settings-body-content-block-heading\">\n<p class=\"gateaux-secs__text\"><b>Gestion de l\u2019acc\u00e8s aux contenus<\/b><\/p>\n<\/p><\/div>\n<p class=\"gateaux-secs__text\">Nous utilisons le service Qiota d\u2019Opper Marketing Suite pour configurer l\u2019activation d\u2019un datawall sur certains de nos contenus (uniquement sur le site web). Ce dispositif destin\u00e9 aux utilisateur\u00b7ices non abonn\u00e9\u00b7es requiert la saisie d\u2019une adresse email pour acc\u00e9der aux contenus concern\u00e9s. En fournissant cette information, l\u2019utilisateur consent \u00e0 sa collecte, son stockage et son utilisation \u00e0 des fins statistiques. Conform\u00e9ment \u00e0 la r\u00e9glementation en vigueur, les utilisateurs disposent d\u2019un droit d\u2019acc\u00e8s, de rectification et de suppression de leurs donn\u00e9es, qu\u2019ils peuvent exercer en contactant dpo@opper.io.<\/p>\n<\/p><\/div>\n<p>                                        <button id=\"js-gateaux-secs-save\" class=\"gateaux-secs__button gateaux-secs__button--fullwidth \">Enregistrer et fermer<\/button>\n                <\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediapart.fr\/journal\/international\/260725\/aucun-signe-d-apaisement-au-troisieme-jour-de-conflit-entre-le-cambodge-et-la-thailande\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les cookies et technologies similaires que nous utilisons sur Mediapart sont de diff\u00e9rentes natures et nous permettent de poursuivre diff\u00e9rentes finalit\u00e9s. Certains sont n\u00e9cessaires au fonctionnement du site et de&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12847"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12848"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}