{"id":12893,"date":"2025-07-27T15:29:42","date_gmt":"2025-07-27T13:29:42","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/27\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-les-moutons-enrages\/"},"modified":"2025-07-27T15:29:42","modified_gmt":"2025-07-27T13:29:42","slug":"etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-les-moutons-enrages","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/27\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-les-moutons-enrages\/","title":{"rendered":"\u00catre B.R.A.V.E en occident d\u00e9cadent au XXI\u00e8me si\u00e8cle \u2013 Les moutons enrag\u00e9s"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Par DJERRAD AMAR<\/p>\n<p><em>\u201cLa mort est solitaire tandis que la servitude est collective.\u201d<br \/><\/em><em>~ Albert Camus, \u201cLa chute\u201d, 1956 ~<\/em><\/p>\n<p><em>\u201cLe gouvernement n\u2019est pas Raison, n\u2019est pas \u00e9loquence, il est force.\u201d<br \/><\/em><em>~ George Washington ~<\/em><\/p>\n<p><em>\u201cJe ne peux pas \u00eatre libre si vous ne l\u2019\u00eates pas.\u201d<br \/><\/em><em>~ Michel Bakounine ~<\/em><\/p>\n<p><em>\u201cLa seule fa\u00e7on de construire le socialisme et de ne pas se faire absorber est d\u2019\u0153uvrer en dehors de l\u2019\u00c9tat, \u00e0 travers des organisations locales et volontaires.\u201d<br \/><\/em><em>~ Gustav Landauer, 1911 ~<\/em><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-463.png\" alt=\"\" class=\"wp-image-168619\" srcset=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-463.png 300w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-463-250x150.png 250w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-463-150x90.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-pagespeed-url-hash=\"2939402567\" onload=\"pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\" onerror=\"this.onerror=null;pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\"\/><\/figure>\n<\/div>\n<p><strong><em>\u00catre B.R.A.V.E au XXI\u00e8me si\u00e8cles en occident g\u00e9nocidaire d\u00e9cadent<\/em><\/strong><\/p>\n<p><em>R\u00e9sister, exister, cr\u00e9er dans la soci\u00e9t\u00e9 en 2025<\/em><\/p>\n<p><strong><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/2025\/07\/21\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-resistance-71\/\" rel=\"noreferrer noopener\" target=\"_blank\">R\u00e9sistance 71<\/a><\/strong><\/p>\n<p><em>20 juillet 2025<\/em><\/p>\n<p>L\u2019occidental moderne lambda se doit de comprendre sans \u00e9quivoque le monde du mensonge, de la tromperie, de la domination et de l\u2019oppression qui l\u2019entoure et dont il est la victime tout autant que les populations domin\u00e9es et exploit\u00e9es par son empire, ce afin de pouvoir agir de mani\u00e8re juste et tout aussi in\u00e9quivoque.<\/p>\n<p>Les peuples occidentaux vivent au sein d\u2019un empire qui a impos\u00e9 au monde sa vision mal\u00e9fique mue par l\u2019id\u00e9ologie marchande anglo-americano-sioniste dominante et en premier lieu \u00e0 ses populations. Nous vivons dans ce qui reste de nations ayant des gouvernements terminalement corrompus, compromis, tra\u00eetres \u00e0 leurs peuples, occup\u00e9s dans ses sph\u00e8res dites \u201csup\u00e9rieures\u201d, par une id\u00e9ologie expansionniste mortif\u00e8re emprunte d\u2019inepties n\u00e9o-malthusiennes, de d\u00e9lires \u00e9litistes transhumanistes et pseudo-religieux dont le sionisme est le dernier avatar colonialiste en date.<\/p>\n<p>L\u2019enjeu aujourd\u2019hui, face au projet eug\u00e9niste n\u00e9o-f\u00e9odal de la caste dirigeante hors-sol d\u00e9vou\u00e9e \u00e0 ses dieux fric et pouvoir de contr\u00f4le absolu, est ni plus ni moins la survie pure et simple de l\u2019\u2019humanit\u00e9.<\/p>\n<p>Nous, les peuples, sommes constamment soumis \u00e0 des agressions et stress croissants ne visant qu\u2019\u00e0 notre extermination et \u00e0 l\u2019asservissement d\u00e9finitif de ceux qui survivront. Nous sommes constamment bombard\u00e9s de mal-bouffe, d\u2019environnements toxiques chimiques, \u00e9lectroniques (champs \u00e9lectro-magn\u00e9tiques 5G etc) d\u2019ing\u00e9nierie sociale visant \u00e0 d\u00e9truire les fondements m\u00eame de notre humanit\u00e9 (culture, sexualit\u00e9, m\u0153urs, relations, mode de vie, spiritualit\u00e9), de \u201cpand\u00e9mies\u201d cr\u00e9\u00e9es de toute pi\u00e8ce en laboratoire ainsi que leurs solutions d\u2019empoisonnement g\u00e9n\u00e9ralis\u00e9 \u00e0 grand renfort d\u2019armement nano-biotechnologique, de crises et chaos sociaux fabriqu\u00e9s ou amplifi\u00e9s, de guerres perp\u00e9tuelles ne visant qu\u2019\u00e0 la destruction et l\u2019exploitation au profit du toujours plus petits nombres, de taxation, de renforcement des mesures coercitives et donc de la tyrannie g\u00e9n\u00e9ralis\u00e9e.<\/p>\n<p><em>Il est un adage qui dit que lorsque la tyrannie devient la loi, la r\u00e9sistance devient un devoir.<\/em> Nous y sommes, une fois de plus dirions-nous.<\/p>\n<p>Ainsi, la philosophe communiste chr\u00e9tienne Simone Weil avait r\u00e9sum\u00e9 la situation de cette fa\u00e7on remarquable : <em>\u201cLa machine de l\u2019\u00c9tat est oppression de par sa nature m\u00eame, ses rouages ne peuvent fonctionner sans broyer les citoyens ; aucune bonne volont\u00e9 ne peut en faire un instrument du bien public, on ne peut l\u2019emp\u00eacher d\u2019opprimer qu\u2019en le brisant.\u201d<\/em><\/p>\n<p>L\u2019\u00e9mancipation ne peut venir qu\u2019en dehors du syst\u00e8me \u00e9tabli, qui ne peut comporter aucune solution puisqu\u2019il est lui-m\u00eame le probl\u00e8me que nous devons r\u00e9soudre dans la fonction du pouvoir. Nous n\u2019\u00e9lirons jamais de \u201cpoliticiens vertueux\u201d qui renverseront la tendance pour r\u00e9tablir justice et paix, car ceci est absolument incompatible avec les objectifs et la logique interne du syst\u00e8me \u00e9tatico-marchand, pervers, dominateur, oppresseur et exploiteur par essence.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"167\" src=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-465.png\" alt=\"\" class=\"wp-image-168621\" srcset=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-465.png 299w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-465-250x140.png 250w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-465-150x84.png 150w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" data-pagespeed-url-hash=\"3528402409\" onload=\"pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\" onerror=\"this.onerror=null;pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\"\/><\/figure>\n<\/div>\n<p>En cons\u00e9quence, une fois ceci clairement compris, admis et int\u00e9gr\u00e9, nous devons agir de mani\u00e8re juste, efficace afin de reprendre le contr\u00f4le de nos vies et de nos destin\u00e9es, de notre capacit\u00e9 d\u00e9cisionnaire sans interm\u00e9diaires parasites. Pour ce faire, nous devons \u00eatre <strong><em>B.R.A.V.E<\/em><\/strong> en ce XXI\u00e8me si\u00e8cle transitoire\u2026<\/p>\n<ul class=\"wp-block-list\">\n<li><strong><em>B<\/em><\/strong> pour <strong><em>Boycott<\/em><\/strong> : LE v\u00e9ritable pouvoir de chacun d\u2019entre nous. Nous pouvons d\u00e9cider \u00e0 tout moment ce que nous pouvons, devons soutenir et refuser le reste. Refuser de jouer le jeu truqu\u00e9, refuser de voter, ultimement refuser de payer, refuser d\u2019acheter produits et services en provenance d\u2019entit\u00e9s n\u00e9fastes, refuser de cautionner le syst\u00e8me mortif\u00e8re dans ses projets destructeurs de contr\u00f4le et d\u2019asservissement, refuser de croire aux dogmes impos\u00e9s, refuser les diktats d\u2019un pouvoir inique n\u2019ayant que la violence pour se faire respecter\u2026 De l\u00e0 jaillira la cr\u00e9ation alternative.<\/li>\n<li><strong><em>R <\/em><\/strong>pour <strong><em>R\u00e9sistance<\/em><\/strong> : le boycott est un des moyens de r\u00e9sister, tr\u00e8s efficace du reste. La r\u00e9sistance n\u2019est pas n\u00e9cessairement violente, bien au contraire, mais elle peut aussi l\u2019\u00eatre, ne nous voilons pas la face. R\u00e9sister c\u2019est reconna\u00eetre ce grand pouvoir que nous avons toutes et tous, individuellement et collectivement : celui d\u2019abord de dire NON ! Haut et fort et de nous unir contre l\u2019injustice et l\u2019oppression syst\u00e9miques. La r\u00e9sistance est inh\u00e9rente \u00e0 toute forme de pouvoir coercitif, elle le suit comme son ombre. Notre tache est, par la r\u00e9sistance et la mise en place de rouages parall\u00e8les, de mettre un terme au syst\u00e8me \u00e0 pouvoir coercitif et de le remplacer par un syst\u00e8me \u00e0 pouvoir non coercitif, seul prouv\u00e9 par l\u2019histoire comme pouvant r\u00e9pondre \u00e0 tous les besoins d\u00e9cisionnaires de l\u2019humanit\u00e9.<\/li>\n<li><strong><em>A<\/em><\/strong> pour <strong><em>Action<\/em><\/strong> : Celle-ci peut prendre bien des formes, mais l\u2019essentiel est qu\u2019elle soit <em>directe<\/em>, en provenance de l\u2019individu qui par son action r\u00e9fl\u00e9chie et d\u00e9cisive, s\u2019associe librement, volontairement \u00e0 d\u2019autres individus ayant la m\u00eame sensibilit\u00e9. L\u2019action individuelle et concert\u00e9e peut aller du boycott \u00e0 la r\u00e9sistance arm\u00e9e selon les circonstances plus ou moins extr\u00eames, en passant par la gr\u00e8ve du z\u00e8le, le sabotage, la diffusion contre-id\u00e9ologique, la mise en pratique collective et autres, pourvu que cela ait pour but d\u2019agir contre le syst\u00e8me \u00e9tatico-marchand en empruntant des voies parall\u00e8les entretenant l\u2019id\u00e9e qu\u2019il ne peut pas y avoir de solution au sein du syst\u00e8me et qu\u2019il est n\u00e9cessaire, vital m\u00eame, d\u2019en sortir si on veut \u00eatre\u2026 efficace.<\/li>\n<li><strong><em>V<\/em><\/strong> pour <strong><em>Versatilit\u00e9<\/em><\/strong> : Soyons multi-dimensionnels, capables de nous adapter rapidement en refusant les dogmes et en agissant pour le bien commun ici et maintenant. Embrassons la compl\u00e9mentarit\u00e9 de notre diversit\u00e9. Construisons des communaut\u00e9s flexibles, faites de compassion, de tol\u00e9rance, de solidarit\u00e9, d\u2019entraide et d\u2019amour, cette chose commune et universelle \u00e0 l\u2019humanit\u00e9 quelque soit la culture dont nous sommes issus. Ceci ne peut se construire qu\u2019hors syst\u00e8me \u00e9tatico-marchand, qui est le parangon de la division, du chaos et de la destruction de ce qui est notre humanit\u00e9 profonde. Construisons \u00e0 l\u2019oppos\u00e9 !<\/li>\n<li><strong><em>E<\/em><\/strong> pour <strong><em>Efficacit\u00e9<\/em><\/strong> : C\u2019est unis que nous vaincrons ! Unis que nous nous organiserons pour le bien commun ! Unis que notre pens\u00e9e, d\u00e9cision, action deviendront des plus efficaces. Plus un syst\u00e8me est complexe, moins il est efficace. L\u2019univers fonctionne selon quelques lois, certes parfois difficile \u00e0 comprendre, \u00e0 rendre intelligible \u00e0 l\u2019esprit humain, mais qui, combin\u00e9es, rendent sa complexit\u00e9 simple et tr\u00e8s efficace dans ses rouages. Une soci\u00e9t\u00e9 bien organis\u00e9e l\u2019est le plus simplement du monde. La soci\u00e9t\u00e9 des soci\u00e9t\u00e9s des associations volontaires, des communes libres volontairement associ\u00e9es et conf\u00e9d\u00e9r\u00e9es dans un effort de d\u00e9veloppement et de bien-\u00eatre commun non pyramidal, sera reconnue, apr\u00e8s analyse, comme mod\u00e8le fondamental pour la soci\u00e9t\u00e9 humaine \u00e9mancip\u00e9e sur le chemin de la pleine r\u00e9alisation de son humanit\u00e9 vraie. La coercition divise et rend les choses les plus simples difficiles et complexes. La non-coercition est fluide et naturelle, elle tend vers l\u2019efficacit\u00e9 dans la simplicit\u00e9. Rien n\u2019est forc\u00e9 dans la nature, tout y est \u00e0 sa place. Dans nos soci\u00e9t\u00e9s coercitives actuelles, et depuis quelques 5000 ans, soit 0,1% de l\u2019existence de l\u2019humanit\u00e9, tout est forc\u00e9, contraint, r\u00e9gul\u00e9 artificiellement, dans une complexit\u00e9 croissante toute aussi futile qu\u2019inefficace, sauf pour une toute petite caste en contr\u00f4le, caste parasitaire dont l\u2019objectif de l\u2019humanit\u00e9 est de se d\u00e9barrasser en faisant passer le syst\u00e8me d\u2019organisation qui la favorise \u00e0 la trappe. Si les hommes cr\u00e9ent le syst\u00e8me, le syst\u00e8me, \u00e0 terme, cr\u00e9e les hommes qui le perp\u00e9tue, c\u2019est une voie \u00e0 deux sens. Virer les \u00e9lites auto-proclam\u00e9es ne sert \u00e0 rien si on ne change pas radicalement de syst\u00e8me de fonctionnement. Tel est le prix de l\u2019efficacit\u00e9. Ce n\u2019est pas du tout cher payer en vue du r\u00e9sultat final, qui ne peut \u00eatre que l\u2019\u00e9mancipation totale et d\u00e9finitive\u2026<\/li>\n<\/ul>\n<p>\u00catre <em>B.R.A.V.E<\/em> doit devenir notre objectif pratique, c\u2019est par cette voie que nous nous \u00e9manciperons \u00e0 tout jamais ! Qu\u2019on se le dise !<\/p>\n<p><em>\u201cL\u2019objectif est le peuple, la soci\u00e9t\u00e9, la communaut\u00e9, la libert\u00e9, la beaut\u00e9, la joie de vivre.\u201d<br \/><\/em><em>~ Gustav Landauer, 1911 ~<\/em><\/p>\n<p><em>\u201cL\u2019anarchie est la reconqu\u00eate de l\u2019individu, c\u2019est la libert\u00e9 du d\u00e9veloppement de l\u2019individu dans un sens normal est harmonieux. On peut la d\u00e9finir en ces mots : l\u2019utilisation spontan\u00e9e de toutes les \u00e9nergies humaines criminellement gaspill\u00e9es par l\u2019\u00c9tat.\u201d<br \/><\/em><em>~ Octave Mirbeau ~<\/em><\/p>\n<p><em>\u201cLe but de la vie est de voir un monde dans un grain de sable, un paradis dans une fleur ; de tenir l\u2019infini dans le creux de votre main et l\u2019\u00e9ternit\u00e9 en une heure.\u201d<br \/><\/em><em>~ William Blake ~<\/em><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-467.png\" alt=\"\" class=\"wp-image-168623\" srcset=\"https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-467.png 300w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-467-250x163.png 250w, https:\/\/lesmoutonsenrages.fr\/wp-content\/uploads\/2025\/07\/image-467-150x98.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-pagespeed-url-hash=\"4117402251\" onload=\"pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\" onerror=\"this.onerror=null;pagespeed.lazyLoadImages.loadIfVisibleAndMaybeBeacon(this);\"\/><\/figure>\n<\/div>\n<p>Propos\u00e9 par A. Djerrad<\/p>\n<p>sur <a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/2025\/07\/21\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-resistance-71\/\" data-type=\"link\" data-id=\"https:\/\/resistance71.wordpress.com\/2025\/07\/21\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle-resistance-71\/\">Resistance 71<\/a><\/p>\n<p><strong><em>Lectures compl\u00e9mentaires :<\/em><\/strong><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2020\/06\/resistance71-du-chemin-de-la-societe-vers-son-humanite-realisee.pdf\"><em>Du chemin de la soci\u00e9t\u00e9 vers son humanit\u00e9 r\u00e9alis\u00e9e, R\u00e9sistance 71<\/em><\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2025\/02\/errico_malatesta_lanarchie.pdf\">Errico_Malatesta_L\u2019anarchie<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2023\/01\/gustav_landauer_ultime_compilation_pour_une_societe_des_societes.pdf\">Gustav_Landauer_Ultime_Compilation_pour_une_societe_des_societes<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2022\/12\/anarqxista_goldman_gustav-landauer-sur-les-relations-anarchistes.pdf\">Anarqxista_Goldman_Gustav-Landauer-sur-les-relations-anarchistes<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2022\/08\/gustave-landauer_appel-au-socialisme-texte-integral.pdf\">Gustave Landauer_Appel au socialisme (texte int\u00e9gral)<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2022\/02\/3-textes-de-reflexions-sur-le-peuple-en-armes-la-resistance-et-la-rebellion.pdf\">3-textes-de-reflexions-sur-le-peuple-en-armes-la-resistance-et-la-rebellion<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2021\/03\/150-ans-de-la-commune-de-paris-recherche-esprit-communard-desesperement.pdf\">150-ans-de-la-commune-de-paris-Recherche-esprit-communard-desesperement<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2021\/03\/mars-1871-mars-2021-lesprit-communard-de-la-commune-en-marche.pdf\">Mars-1871-Mars-2021-lesprit-communard-de-la-commune-en-marche<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2018\/03\/dieu-et-letat_bakounine.pdf\">Dieu et lEtat_Bakounine<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2018\/03\/kropotkine_entraide_facteur_de_levolution.pdf\">Kropotkine_Entraide_facteur_de_levolution<\/a><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/resistance71.wordpress.com\/wp-content\/uploads\/2017\/01\/petit_prc3a9cis_sur_la_socic3a9tc3a9_et_lc3a9tat.pdf\">petit_precis_sur_la_societe_et_letat<\/a><\/p>\n<p>Tous les articles, la tribune libre et les commentaires sont sous la responsabilit\u00e9 de leurs auteurs. Les Moutons Enrag\u00e9s ne sauraient \u00eatre tenus responsables de leur contenu ou orientation en les publiant ou republiant sur le site.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/lesmoutonsenrages.fr\/2025\/07\/22\/etre-b-r-a-v-e-en-occident-decadent-au-xxieme-siecle\/\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par DJERRAD AMAR \u201cLa mort est solitaire tandis que la servitude est collective.\u201d~ Albert Camus, \u201cLa chute\u201d, 1956 ~ \u201cLe gouvernement n\u2019est pas Raison, n\u2019est pas \u00e9loquence, il est force.\u201d~&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12893"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12894"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}