{"id":12906,"date":"2025-07-27T22:05:53","date_gmt":"2025-07-27T20:05:53","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/27\/la-retenue-collinaire-de-la-clusaz-interdite-par-le-tribunal\/"},"modified":"2025-07-27T22:05:53","modified_gmt":"2025-07-27T20:05:53","slug":"la-retenue-collinaire-de-la-clusaz-interdite-par-le-tribunal","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/27\/la-retenue-collinaire-de-la-clusaz-interdite-par-le-tribunal\/","title":{"rendered":"La retenue collinaire de La Clusaz interdite par le tribunal"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/49974670032_db7482e25f_5k_1_1_-17e4d.jpg?1753357294\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>C&rsquo;est une victoire contre l&rsquo;industrie du ski et l&rsquo;accaparement de l&rsquo;eau. Le projet de retenue collinaire de Beauregard \u00e0 La Clusaz (Haute-Savoie) a \u00e9t\u00e9 retoqu\u00e9 le 23\u00a0juillet par le tribunal administratif de Grenoble. <br class=\"autobr\" \/><br \/>\nDepuis 2020, la station de ski souhaitait implanter cette retenue d&rsquo;eau de 148\u00a0000\u00a0m\u00b3 pour produire de la neige de culture. Ses travaux auraient n\u00e9cessit\u00e9 de d\u00e9fricher 8\u00a0hectares d&rsquo;habitats naturels aux d\u00e9pens des 55\u00a0esp\u00e8ces prot\u00e9g\u00e9es locales. Le chantier a \u00e9t\u00e9 frein\u00e9 par\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/La-retenue-collinaire-de-La-Clusaz-interdite-par-le-tribunal?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Breves-20\" rel=\"directory\">En bref<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Luttes\" rel=\"tag\">Luttes<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Eau-rivieres-oceans\" rel=\"tag\">Eau et rivi\u00e8res<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Justice\" rel=\"tag\">Justice<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Montagne\" rel=\"tag\">Montagne<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/La-retenue-collinaire-de-La-Clusaz-interdite-par-le-tribunal\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une victoire contre l&rsquo;industrie du ski et l&rsquo;accaparement de l&rsquo;eau. Le projet de retenue collinaire de Beauregard \u00e0 La Clusaz (Haute-Savoie) a \u00e9t\u00e9 retoqu\u00e9 le 23\u00a0juillet par le tribunal&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12906","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12906"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12906\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}