{"id":12920,"date":"2025-07-28T04:08:19","date_gmt":"2025-07-28T02:08:19","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2025\/07\/28\/recyclage-de-vetements-le-modele-du-relais-en-peril\/"},"modified":"2025-07-28T04:08:19","modified_gmt":"2025-07-28T02:08:19","slug":"recyclage-de-vetements-le-modele-du-relais-en-peril","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2025\/07\/28\/recyclage-de-vetements-le-modele-du-relais-en-peril\/","title":{"rendered":"Recyclage de v\u00eatements: le mod\u00e8le du Relais en p\u00e9ril"},"content":{"rendered":"<p> <br \/>\n<br \/>Le Relais, acteur majeur de la collecte textile en France, est en crise depuis plusieurs mois. Face \u00e0 l\u2019augmentation de v\u00eatements donn\u00e9s, l\u2019entreprise d\u2019insertion assure n\u2019avoir plus les moyens de remplir sa mission. \u00c0 Saint-Hilaire-lez-Cambrai, les salari\u00e9s s\u2019inqui\u00e8tent pour leur avenir.<br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.mediapart.fr\/journal\/economie-et-social\/270725\/recyclage-de-vetements-le-modele-du-relais-en-peril\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Relais, acteur majeur de la collecte textile en France, est en crise depuis plusieurs mois. Face \u00e0 l\u2019augmentation de v\u00eatements donn\u00e9s, l\u2019entreprise d\u2019insertion assure n\u2019avoir plus les moyens de&hellip; <\/p>\n","protected":false},"author":1,"featured_media":12921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=12920"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/12920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/12921"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=12920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=12920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=12920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}