{"id":21724,"date":"2026-01-01T12:08:35","date_gmt":"2026-01-01T11:08:35","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/01\/01\/les-oppositions-raillent-les-voeux-inutiles-demmanuel-macron-rt-en-francais\/"},"modified":"2026-01-01T12:08:35","modified_gmt":"2026-01-01T11:08:35","slug":"les-oppositions-raillent-les-voeux-inutiles-demmanuel-macron-rt-en-francais","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/01\/01\/les-oppositions-raillent-les-voeux-inutiles-demmanuel-macron-rt-en-francais\/","title":{"rendered":"Les oppositions raillent les v\u0153ux \u00abinutiles\u00bb d\u2019Emmanuel Macron \u2014 RT en fran\u00e7ais"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/mf.b37mrtl.ru\/french\/images\/2026.01\/thumbnail\/695642a56f7ccc23dc75399b.jpg\" \/><\/p>\n<div>\n<p class=\"text__summary\">\n                                        Les v\u0153ux du pr\u00e9sident de la R\u00e9publique pour 2026, prononc\u00e9s mercredi soir depuis l\u2019\u00c9lys\u00e9e, ont suscit\u00e9 un toll\u00e9 chez les oppositions. Qualifi\u00e9s de \u00abmots vides\u00bb et de \u00abbanalit\u00e9s convenues\u00bb, ils sont accus\u00e9s de manquer de substance face \u00e0 l\u2019instabilit\u00e9 politique et aux d\u00e9fis internationaux, \u00e0 seize mois de la pr\u00e9sidentielle.\n                                    <\/p>\n<p>Comme chaque ann\u00e9e, Emmanuel Macron a trac\u00e9 une feuille de route pour 2026 lors de son allocution t\u00e9l\u00e9vis\u00e9e, mais les r\u00e9actions des figures politiques ont \u00e9t\u00e9 majoritairement critiques, d&rsquo;<a target=\"_blank\" href=\"https:\/\/francais.rt.com\/france\/128929-voeux-crepusculaires-demmanuel-macron-pour\">un discours per\u00e7u comme d\u00e9connect\u00e9 et cr\u00e9pusculaire<\/a>.<\/p>\n<h2>Des oppositions\u00a0unanimement critiques<\/h2>\n<p>Les oppositions n\u2019ont pas tard\u00e9 \u00e0 exprimer leur d\u00e9ception sur X, o\u00f9 les commentaires acerbes ont fus\u00e9 d\u00e8s la fin de l\u2019allocution. Jean-Luc M\u00e9lenchon, chef de file de La France insoumise, a ironis\u00e9 : \u00ab\u00a0Lui-m\u00eame semblait pr\u00eat \u00e0 s\u2019endormir en parlant\u00a0\u00bb, ajoutant que \u00ab\u00a0quelque chose est cass\u00e9 en lui et avec le pays\u00a0\u00bb. Dans un tweet mordant, il s\u2019interroge sur qui pourrait se sentir \u00ab\u00a0concern\u00e9 par cette litanie d\u2019annonces d\u00e9j\u00e0 cent fois trahies et de mots vides\u00a0\u00bb.<\/p>\n<div class=\"rtcode\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">Voeux du Pr\u00e9sident. <br \/>Qui se sent concern\u00e9 par cette litanie d&rsquo;annonces d\u00e9j\u00e0 cent fois trahies et de mots vides ? Lui-m\u00eame semblait pr\u00eat \u00e0 s&rsquo;endormir en parlant. Quelque chose est cass\u00e9 en lui et avec le pays.<\/p>\n<p>\u2014 Jean-Luc M\u00e9lenchon (@JLMelenchon) <a target=\"_blank\" href=\"https:\/\/twitter.com\/JLMelenchon\/status\/2006445094963130422?ref_src=twsrc%5Etfw\">December 31, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><a target=\"_blank\" href=\"https:\/\/x.com\/JLMelenchon\/status\/2006445094963130422?s=20\"\/>De son c\u00f4t\u00e9, Marine Tondelier, secr\u00e9taire nationale des Ecologistes et candidate \u00e0 la pr\u00e9sidentielle 2027, a confi\u00e9 peiner\u00a0 \u00ab \u00e0 trouver les mots suite \u00e0 cette allocution\u00a0\u00bb, taclant un pr\u00e9sident qui \u00ab\u00a0semble lui-m\u00eame avoir l\u00e2ch\u00e9 l\u2019affaire\u00a0\u00bb. Elle a insist\u00e9\u00a0:\u00ab\u00a0\u201cNotre pays tient\u201c. Vraiment ? (&#8230;) En 2026, nous nous battrons pour \u00e9viter de nouveaux reculs et pr\u00e9parer l\u2019alternance\u00a0\u00bb.<\/p>\n<p>\u00c9ric Coquerel, d\u00e9put\u00e9 insoumis et pr\u00e9sident de la commission des Finances, a \u00e9voqu\u00e9 les v\u0153ux \u00ab\u00a0inutiles d\u2019un Pr\u00e9sident toujours aussi satisfait de lui-m\u00eame\u00a0\u00bb,\u00a0dont le \u00ab\u00a0bilan s\u2019assombrit pourtant chaque ann\u00e9e\u00a0\u00bb. Il a rappel\u00e9 que Macron \u00ab\u00a0est le seul \u00e0 oublier \u00e0 quel point il est minoritaire dans le peuple et au Parlement\u00a0\u00bb, concluant avec espoir\u00a0:\u00ab\u00a0Heureusement ce sont, au pire, ses avant-derniers v\u0153ux\u00a0\u00bb.<\/p>\n<p>\u00c0 droite, \u00c9ric Ciotti, d\u00e9put\u00e9 LR, a estim\u00e9 que \u00ab\u00a0le seul v\u0153u que l\u2019on puisse adresser \u00e0 la France, c\u2019est le d\u00e9part\u00a0\u00bb du pr\u00e9sident, accusant l\u2019allocution d\u2019enfoncer \u00ab\u00a0des portes ouvertes en encha\u00eenant les lieux communs et les banalit\u00e9s convenues\u00a0\u00bb.<\/p>\n<div class=\"rtcode\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">Une nouvelle fois ce soir, Emmanuel Macron a enfonc\u00e9 des portes ouvertes en encha\u00eenant les lieux communs et les banalit\u00e9s convenues.<\/p>\n<p>Le seul v\u0153ux que l\u2019on puisse adresser \u00e0 la France c\u2019est son d\u00e9part pour engager le redressement national !<\/p>\n<p>\u2014 Eric Ciotti (@eciotti) <a target=\"_blank\" href=\"https:\/\/twitter.com\/eciotti\/status\/2006447184284393876?ref_src=twsrc%5Etfw\">December 31, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><a target=\"_blank\" href=\"https:\/\/x.com\/eciotti\/status\/2006447184284393876?s=20\"\/>Bruno Retailleau, pr\u00e9sident des R\u00e9publicains, a souscrit au souhait d\u2019une \u00ab\u00a0ann\u00e9e 2026 utile\u00a0\u00bb, mais a tacl\u00e9 :\u00ab\u00a0Encore faudra-t-il pour cela ne pas sacrifier l\u2019avenir au pr\u00e9sent\u00a0\u00bb, promettant de prendre \u00ab\u00a0toute (sa) part\u00a0\u00bb dans les d\u00e9fis \u00e0 venir.<\/p>\n<p>Marine Le Pen et Jordan Bardella n\u2019ont pas comment\u00e9 l\u2019intervention pr\u00e9sidentielle, se contentant de publier leurs propres v\u0153ux en vid\u00e9o.<\/p>\n<p>Quant \u00e0 l\u2019eurod\u00e9put\u00e9e Sarah Knafo, elle a raill\u00e9\u00a0: \u00ab C\u2019\u00e9tait court\u2026 mais pas intense. J\u2019ai trouv\u00e9 que c\u2019\u00e9tait un discours Chat GPT. Pas d\u2019\u00e2me, pas de souffle, pas d\u2019id\u00e9e\u00a0\u00bb.<\/p>\n<div class=\"rtcode\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">Emmanuel Macron, c\u2019\u00e9tait court\u2026 mais pas intense. <\/p>\n<p>J\u2019ai trouv\u00e9 que c\u2019\u00e9tait un discours Chat GPT. Pas d\u2019\u00e2me, pas de souffle, pas d\u2019id\u00e9e. Il est temps de l\u00e2cher la rampe. <a target=\"_blank\" href=\"https:\/\/t.co\/eJINTiaG8N\">pic.twitter.com\/eJINTiaG8N<\/a><\/p>\n<p>\u2014 Sarah Knafo (@knafo_sarah) <a target=\"_blank\" href=\"https:\/\/twitter.com\/knafo_sarah\/status\/2006454274503618844?ref_src=twsrc%5Etfw\">December 31, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><a target=\"_blank\" href=\"https:\/\/x.com\/knafo_sarah\/status\/2006454274503618844?s=20\"\/>Ces r\u00e9actions font \u00e9cho \u00e0 un discours pr\u00e9sidentiel ax\u00e9 sur l\u2019unit\u00e9, la d\u00e9centralisation et des priorit\u00e9s comme le service national, la r\u00e9gulation des r\u00e9seaux sociaux et la loi sur la fin de vie. Pourtant, les oppositions y voient un manque de vision concr\u00e8te, amplifi\u00e9 par un contexte de guerre en Ukraine et d\u2019ing\u00e9rences \u00e9trang\u00e8res potentielles pour 2027. Thomas Portes, d\u00e9put\u00e9 LFI, a r\u00e9sum\u00e9 l\u2019humeur g\u00e9n\u00e9rale dans un tweet :\u00ab\u00a0Des v\u0153ux cr\u00e9pusculaires et vides pour un pr\u00e9sident de la R\u00e9publique isol\u00e9 et dont la parole n\u2019a plus aucune l\u00e9gitimit\u00e9. La meilleur chose \u00e0 faire, c\u2019est qu\u2019il parte, et le plus rapidement possible\u00a0\u00bb.<\/p>\n<div class=\"rtcode\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">Des v\u0153ux cr\u00e9pusculaires et vides pour un pr\u00e9sident de la R\u00e9publique isol\u00e9 et dont la parole n\u2019a plus aucune l\u00e9gitimit\u00e9. Emmanuel Macron a exprim\u00e9 le souhait que l\u2019ann\u00e9e 2026 soit utile au pays. La meilleur chose \u00e0 faire c\u2019est qu\u2019il parte, et le plus rapidement possible. Il a\u2026<\/p>\n<p>\u2014 Thomas Portes (@Portes_Thomas) <a target=\"_blank\" href=\"https:\/\/twitter.com\/Portes_Thomas\/status\/2006451411937009811?ref_src=twsrc%5Etfw\">December 31, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><a target=\"_blank\" href=\"https:\/\/x.com\/Portes_Thomas\/status\/2006451411937009811?s=20\"\/>Au-del\u00e0 des politiques, les internautes ont relay\u00e9 ces critiques, avec des articles de m\u00e9dias comme Franceinfo et BFM TV, d\u2019ordinaire plut\u00f4t conciliants avec le pr\u00e9sident, titrant sur des v\u0153ux \u00ab\u00a0tristes\u00a0\u00bb,\u00ab\u00a0d\u00e9cevants\u00a0\u00bb et \u00ab\u00a0sans relief\u00a0\u00bb, illustrant un foss\u00e9 croissant entre l\u2019\u00c9lys\u00e9e et l\u2019opinion publique.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/francais.rt.com\/france\/128934-oppositions-raillent-voeux-inutiles-emmanuel-macron\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les v\u0153ux du pr\u00e9sident de la R\u00e9publique pour 2026, prononc\u00e9s mercredi soir depuis l\u2019\u00c9lys\u00e9e, ont suscit\u00e9 un toll\u00e9 chez les oppositions. Qualifi\u00e9s de \u00abmots vides\u00bb et de \u00abbanalit\u00e9s convenues\u00bb, ils&hellip; <\/p>\n","protected":false},"author":1,"featured_media":21725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/21724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=21724"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/21724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/21725"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=21724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=21724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=21724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}