{"id":21726,"date":"2026-01-01T12:41:41","date_gmt":"2026-01-01T11:41:41","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/01\/01\/stop-a-la-repression-des-militants-et-ecrivains-pacifistes\/"},"modified":"2026-01-01T12:41:41","modified_gmt":"2026-01-01T11:41:41","slug":"stop-a-la-repression-des-militants-et-ecrivains-pacifistes","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/01\/01\/stop-a-la-repression-des-militants-et-ecrivains-pacifistes\/","title":{"rendered":"Stop \u00e0 la r\u00e9pression des militants et \u00e9crivains pacifistes !"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<p>En avril 2023, Pierre-Olivier Poyard\u00a0a d\u2019abord fait l\u2019objet d\u2019une enqu\u00eate de gendarmerie. Il en a \u00e9t\u00e9 inform\u00e9 le 5 mai 2023, soit deux jours avant le 1er festival \u00ab\u00a0Faites la Paix\u00a0\u00bb, festival organis\u00e9 par le Mouvement de la Paix au th\u00e9\u00e2tre de verdure de Plainfaing dans les Vosges, dont il est une des chevilles ouvri\u00e8res. Ce fut malgr\u00e9 cela un grand succ\u00e8s\u00a0: la compagnie \u00ab\u00a0Jolie M\u00f4me\u00a0\u00bb y a en effet r\u00e9uni des centaines de personnes le dimanche 7 mai 2023. Deux jours plus tard, le mardi 9 mai 2023, le tr\u00e9sorier national du Mouvement de la Paix a \u00e9t\u00e9 plac\u00e9 en garde \u00e0 vue. Les gendarmes en ont profit\u00e9 pour l\u2019emmener menott\u00e9 \u00e0 l\u2019h\u00f4pital psychiatrique de Mirecourt afin de le faire avouer\u00a0: il a d\u00fb avouer \u00e0 un psychiatre qu\u2019il \u00e9tait une personne LGBT, ce qui est une forme d\u2019homophobie, qu\u2019on appelle \u00ab\u00a0un coming out forc\u00e9\u00a0\u00bb.<\/p>\n<p><strong>Quand l\u2019homophobie et l\u2019antisyndicalisme redoublent la chasse aux pacifistes<\/strong><\/p>\n<p>C\u2019est que, quelques-uns de ses coll\u00e8gues du lyc\u00e9e agricole de Mirecourt, dans les Vosges, une petite minorit\u00e9, affili\u00e9e \u00e0 un syndicat minoritaire, quand ils ont d\u00e9couvert que Pierre-Olivier Poyard \u00e9tait une personne LGBT, l\u2019ont d\u00e9nonc\u00e9 en gendarmerie. Sans aucune preuve, sans qu\u2019aucun \u00e9l\u00e8ve ne se soit jamais plaint de lui, ni aucun parent, sans aucun rapport d\u2019incident, ils ont consid\u00e9r\u00e9 qu\u2019il avait une mauvaise influence sur les jeunes, en tant que personne \u00ab\u00a0atypique\u00a0\u00bb. Certains \u00e9taient jaloux de son activit\u00e9 d\u2019\u00e9crivain pacifiste\u00a0; d\u2019autres n\u2019acceptaient pas son orientation sexuelle, qu\u2019ils venaient de d\u00e9couvrir. Le pire, c\u2019est que le Procureur des Vosges, consid\u00e9rant que ces accusations discriminatoires \u00e9taient infond\u00e9es, a pourtant ouvert une proc\u00e9dure pour \u00ab\u00a0harc\u00e8lement moral\u00a0\u00bb contre le responsable pacifiste\u00a0: une coll\u00e8gue, qui l\u2019a calomni\u00e9 sur sa sexualit\u00e9,\u00a0l\u2019a \u00e9galement\u00a0accus\u00e9 \u00ab\u00a0d\u2019oppression syndicale\u00a0\u00bb.<\/p>\n<p>Cette accusation antisyndicale a men\u00e9 Pierre-Olivier Poyard au Tribunal correctionnel d\u2019\u00c9pinal, le 2 septembre 2025, accompagn\u00e9 d\u2019une cinquantaine de militants, dont des membres du bureau national de son syndicat, le SNETAP-FSU. Le 7 octobre suivant, il a \u00e9t\u00e9 relax\u00e9. Les juges ont consid\u00e9r\u00e9 que proposer l\u2019adh\u00e9sion \u00e0 une coll\u00e8gue n\u2019\u00e9tait pas du \u00ab\u00a0harc\u00e8lement moral\u00a0\u00bb. Le procureur n\u2019a pas fait appel de cette d\u00e9cision. La proc\u00e9dure p\u00e9nale\u00a0s\u2019est donc conclue sur une victoire judiciaire du pacifiste. Aucune poursuite n\u2019a \u00e9t\u00e9 engag\u00e9e suite aux autres calomnies, sans preuves, ni victimes, ni t\u00e9moins. Mais la rumeur, ce poison sans rem\u00e8de, \u00e0 compl\u00e8tement d\u00e9truit le militant de la paix, qui est toujours en d\u00e9pression. Dans ces conditions d\u2019ins\u00e9curit\u00e9 et d\u2019injustice, il ne sait pas s\u2019il pourra retourner enseigner la culture de paix en classe, un jour.<\/p>\n<p><strong>Un acharnement au niveau familial et administratif contre un militant pacifiste<\/strong><\/p>\n<p>Ce n\u2019est pas tout&#8230; d\u2019autres proc\u00e9dures ont \u00e9t\u00e9 lanc\u00e9es contre le responsable pacifiste. Certains des coll\u00e8gues accusateurs ont pris langue avec l\u2019ex-femme de Pierre-Olivier Poyard pour partager leurs mensonges. A cause de cela et pendant 4 mois, on a emp\u00each\u00e9 \u00e0 ce militant de la paix de voir ses enfants. Mais l\u00e0 aussi, les Juges aux Affaires Familiales ont fait respecter les droits, parentaux cette fois, de l\u2019activiste, \u00e0 3 reprises, en avril 2024, mars et avril 2025. La partie adverse a \u00e9t\u00e9 condamn\u00e9e \u00e0 verser plus de 1700 euros d\u2019indemnit\u00e9s \u00e0 ce p\u00e8re de deux enfants&#8230; Il peut d\u00e9sormais continuer \u00e0 les voir, \u00e0 les \u00e9lever et \u00e0 leur transmettre ses valeurs, comme la culture de la paix et de la non-violence.<\/p>\n<p>En outre, l\u2019acharnement contre le syndicaliste pacifiste a pris \u00e9galement la forme d\u2019une enqu\u00eate administrative de sa cheffe d\u2019\u00e9tablissement qui, apr\u00e8s avoir pris connaissance de sa qualit\u00e9 de personne LGBT, l\u2019a d\u00e9crit dans un rapport du 16 juin 2023 comme \u00ab\u00a0focalis\u00e9 sur le sexe\u00a0\u00bb, et a \u00e9voqu\u00e9 \u00ab\u00a0la longueur du sexe des hommes noirs.\u00a0\u00bb Elle d\u00e9peint l\u2019enseignant comme un danger pour \u00ab\u00a0la sant\u00e9 psychique\u00a0\u00bb des \u00e9l\u00e8ves. En r\u00e9alit\u00e9, c\u2019est \u00e0 son enseignement pacifiste et \u00e0 son engagement syndical qu\u2019elle a voulu mettre un terme. En effet, Pierre-Olivier Poyard a d\u00e9velopp\u00e9 tout un projet culturel autour de la paix, intitul\u00e9 \u00ab\u00a0Agri-culture de Paix\u00a0\u00bb. Il a \u00e9galement obtenu, par l\u2019action syndicale, plus de 25000 euros pour trois de ses coll\u00e8gues, dont deux AESH, Accompagnantes d\u2019\u00e9l\u00e8ves en situation de handicap.<\/p>\n<p><strong>Une r\u00e9pression au plus haut niveau du Minist\u00e8re de l\u2019Agriculture<\/strong><\/p>\n<p>Certainement pour couvrir le rapport homophobe et raciste de sa cheffe d\u2019\u00e9tablissement, l\u2019administration minist\u00e9rielle a fini par convoquer Pierre-Olivier Poyard le 24 juin 2024 \u00e0 une Commission Administrative Paritaire Disciplinaire nationale, \u00e0 Paris. Co\u00efncidence\u00a0? Dans le m\u00eame temps sortait le 2e livre de l\u2019auteur pacifiste\u00a0: \u00ab\u00a0\u00c9cologie et Paix\u00a0\u00bb, sous-titr\u00e9\u00a0: \u00ab\u00a0Pour sauver notre Terre, arr\u00eatez les guerres\u00a0!\u00a0\u00bb Le Minist\u00e8re aurait voulu saboter la sortie de cet ouvrage pacifiste qu\u2019il ne s\u2019en serait pas pris autrement. L\u2019\u00e9crivain y explique que la catastrophe \u00e9cologique en cours n\u00e9cessite une v\u00e9ritable R\u00e9volution, politique et sociale, pour en finir avec les militarismes, qui ne font qu\u2019accentuer la destruction de la Terre et de l\u2019Humanit\u00e9.<\/p>\n<p>Lors de cette commission disciplinaire nationale, la totalit\u00e9 des repr\u00e9sentants syndicaux ont d\u00e9fendu le syndicaliste pacifiste et demand\u00e9 \u00e0 l\u2019administration de cesser toute proc\u00e9dure contre lui&#8230; Mais un mois plus tard, le 23 juillet 2024, le Secr\u00e9tariat G\u00e9n\u00e9ral du Minist\u00e8re de l\u2019Agriculture, faisant fi de la d\u00e9mocratie sociale, a sanctionn\u00e9 Pierre-Olivier Poyard pour \u00ab\u00a0harc\u00e8lement moral\u00a0\u00bb, \u00e0 une \u00ab\u00a0exclusion de fonction pour une dur\u00e9e de 8 jours, dont 4 avec sursis\u00a0\u00bb. Pour justifier cela, le Minist\u00e8re a stigmatis\u00e9 l\u2019engagement du fonctionnaire et le fait qu\u2019il syndique ses coll\u00e8gues&#8230; ce que les juges du Tribunal correctionnel d\u2019\u00c9pinal ont consid\u00e9r\u00e9 comme ne constituant pas des faits de \u00ab\u00a0harc\u00e8lement moral\u00a0\u00bb. En d\u2019autres termes, ces juges professionnels ont d\u00e9jug\u00e9 la sanction disciplinaire impos\u00e9e \u00e0 l\u2019enseignant par la haute administration. Depuis le 7 octobre 2025, cela fait d\u00e9j\u00e0 plusieurs mois que le Minist\u00e8re de l\u2019Agriculture aurait du lever cette sanction injuste.<\/p>\n<p><strong>Un Minist\u00e8re qui persiste dans la r\u00e9pression d\u2019un militant de la paix<\/strong><\/p>\n<p>Malheureusement pour Pierre-Olivier Poyard, le Minist\u00e8re de l\u2019Agriculture ne s\u2019est pas arr\u00eat\u00e9 l\u00e0 et a continu\u00e9 \u00e0 s\u2019acharner sur lui. Alors qu\u2019il terminait son arr\u00eat de travail, apr\u00e8s un an et demi de Cong\u00e9 de Longue Maladie pour d\u00e9pression, le Minist\u00e8re l\u2019a de nouveau sanctionn\u00e9 par une d\u00e9cision d\u2019un mois \u00ab\u00a0d\u2019interdiction d\u2019acc\u00e8s\u00a0\u00bb \u00e0 son \u00e9tablissement en mars 2025. Nouvelle humiliation. Malgr\u00e9 plusieurs signalements, depuis juin 2023, il refuse d\u2019engager une enqu\u00eate administrative sur la discrimination v\u00e9cue par le pacifiste LGBT, fid\u00e8le au drapeau arc-en-ciel. Au contraire, dans un rapport dat\u00e9 du 17 avril 2024, il \u00e9crit que d\u00e9noncer \u00eatre victime d\u2019homophobie serait \u00ab\u00a0un manquement au devoir de r\u00e9serve\u00a0\u00bb et au \u00ab\u00a0devoir d\u2019int\u00e9grit\u00e9 des agents publics\u00a0\u00bb. Cette position du Minist\u00e8re est tout simplement contraire aux lois et aux droits des fonctionnaires.<\/p>\n<p>En r\u00e9alit\u00e9, cette discrimination ne concerne pas que l\u2019orientation sexuelle. En effet, la d\u00e9pression dans laquelle a \u00e9t\u00e9 plong\u00e9 Pierre-Olivier Poyard l\u2019a conduit \u00e0 se remettre profond\u00e9ment en cause. En mars 2025, il a fait la d\u00e9marche de r\u00e9aliser des tests psychologiques approfondis. Ceux-ci se sont conclus par un diagnostic de HPI-TSA (Haut-Potentiel Intellectuel et Trouble du Spectre Autistique) et une RQTH (Reconnaissance de la Qualit\u00e9 du Travailleur Handicap\u00e9) le 11 septembre 2025. Faire reconna\u00eetre un handicap est toujours un cheminement difficile&#8230; Cependant, malgr\u00e9 cela, aucune proposition d\u2019adaptation de son poste de travail n\u2019a \u00e9t\u00e9 faite \u00e0 l\u2019enseignant. Au contraire, on l\u2019a mis au placard dans une \u00ab\u00a0mission r\u00e9gionale\u00a0\u00bb pour l\u2019emp\u00eacher d\u2019enseigner. Pour l\u2019\u00c9tat fran\u00e7ais, il faut faire taire les voix pacifistes par tous les moyens&#8230; et les \u00e9carter de la jeunesse.<\/p>\n<p><strong>Le comit\u00e9 de soutien \u00e0 Pierre-Olivier Poyard se bat pour sa r\u00e9habilitation<\/strong><\/p>\n<p>Apr\u00e8s bient\u00f4t 3 ans de pers\u00e9cutions, le Minist\u00e8re de l\u2019Agriculture doit respecter les d\u00e9cisions de justice et la Loi. Son acharnement contre le responsable national du Mouvement de la Paix et auteur pacifiste doit cesser. Le Minist\u00e8re doit le r\u00e9int\u00e9grer sur son poste d\u2019enseignant, sans discriminations, ni sanctions. Il doit l\u2019indemniser pour le pr\u00e9judice subi, pr\u00e8s de 3 ans de proc\u00e9dures iniques.<\/p>\n<p>Le \u00ab\u00a0Comit\u00e9 de soutien pour la r\u00e9habilitation de Pierre-Olivier Poyard\u00a0\u00bb appelle toustes les citoyennes et les citoyens \u00e9pris des libert\u00e9s et des droits humains\u00a0:<\/p>\n<p><strong>&#8211; \u00e0 signer la p\u00e9tition sur change.org\u00a0:<\/strong> <a target=\"_blank\" href=\"https:\/\/www.change.org\/non_homophobie_discriminations_agriculture\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/www.change.org\/non_homophobie_discriminations_agriculture<\/a><\/p>\n<p><strong>&#8211; \u00e0 participer \u00e0 la cagnotte lanc\u00e9e sur helloasso\u00a0:<\/strong> <a target=\"_blank\" href=\"https:\/\/www.helloasso.com\/associations\/comite-des-vosges-du-mouvement-de-la-paix\/collectes\/campagne-de-financement-pour-le-comite-de-soutien-a-po-poyard\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/www.helloasso.com\/associations\/comite-des-vosges-du-mouvement-de-la-paix\/collectes\/campagne-de-financement-pour-le-comite-de-soutien-a-po-poyard<\/a><\/p>\n<p><strong>&#8211; \u00e0 commander le dernier livre de Pierre-Olivier Poyard sur la boutique de la Paix\u00a0:<\/strong> <a target=\"_blank\" href=\"https:\/\/boutiquedelapaix.com\/livres-agenda\/797-livre-ecologie-et-paix.html\" class=\"spip_url spip_out auto\" rel=\"nofollow external\">https:\/\/boutiquedelapaix.com\/livres-agenda\/797-livre-ecologie-et-paix.html<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.legrandsoir.info\/stop-a-la-repression-des-militants-et-ecrivains-pacifistes.html\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En avril 2023, Pierre-Olivier Poyard\u00a0a d\u2019abord fait l\u2019objet d\u2019une enqu\u00eate de gendarmerie. Il en a \u00e9t\u00e9 inform\u00e9 le 5 mai 2023, soit deux jours avant le 1er festival \u00ab\u00a0Faites la&hellip; <\/p>\n","protected":false},"author":1,"featured_media":21727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/21726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=21726"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/21726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/21727"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=21726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=21726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=21726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}