{"id":27750,"date":"2026-05-13T01:09:35","date_gmt":"2026-05-12T23:09:35","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/un-aspirateur-sous-marin-remporte-le-concours-lepine-2026\/"},"modified":"2026-05-13T01:09:35","modified_gmt":"2026-05-12T23:09:35","slug":"un-aspirateur-sous-marin-remporte-le-concours-lepine-2026","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/un-aspirateur-sous-marin-remporte-le-concours-lepine-2026\/","title":{"rendered":"Un aspirateur sous-marin remporte le concours L\u00e9pine 2026"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>Parmi les 250 inventions pr\u00e9sent\u00e9es le dimanche 10 mai \u00e0 la Foire de Paris, il y en a une qui a capt\u00e9 l&rsquo;attention du jury pour sa port\u00e9e \u00e9cologique et technique. Mr Turbino, un dispositif capable d&rsquo;aspirer les d\u00e9chets et les microplastiques des oc\u00e9ans, a d\u00e9croch\u00e9 le premier prix du prestigieux concours L\u00e9pine.<\/strong><\/p>\n<p>Alan Mario D&rsquo;Alfonso Peral, l&rsquo;inventeur derri\u00e8re cette machine, a mis des ann\u00e9es \u00e0 peaufiner son concept. Il ne s&rsquo;agit pas d&rsquo;un simple filet tra\u00eenant derri\u00e8re un bateau. <a target=\"_blank\" href=\"https:\/\/mrturbino.com\/\">Mr Turbino<\/a> fonctionne gr\u00e2ce \u00e0 une technologie brevet\u00e9e bas\u00e9e sur un vortex \u00e0 basse pression. Cette m\u00e9thode ing\u00e9nieuse permet de collecter les polluants sans aspiration continue, donc sans que le robot ne perturbe la vie autour de lui.<\/p>\n<p>L&rsquo;appareil peut donc op\u00e9rer \u00e0 proximit\u00e9 de zones sensibles comme les herbiers marins ou les r\u00e9cifs rocheux. L\u00e0 o\u00f9 les m\u00e9thodes traditionnelles risqueraient d&rsquo;endommager l&rsquo;\u00e9cosyst\u00e8me, Mr Turbino passe inaper\u00e7u. Les organisateurs du concours ont salu\u00e9 une invention \u00e0 la fois \u00e9cologique, connect\u00e9e et citoyenne. Le terme citoyen renvoie \u00e0 la possibilit\u00e9 pour les particuliers ou les associations locales de s&rsquo;approprier l&rsquo;outil.<\/p>\n<p>Alors que la pollution plastique des oc\u00e9ans constitue l&rsquo;un des d\u00e9fis majeurs de notre si\u00e8cle, que les microplastiques contaminent la cha\u00eene alimentaire, voil\u00e0 que l&rsquo;aspirateur de fonds marins rejoint les inventions utiles. Le stylo \u00e0 bille, la tondeuse \u00e0 gazon ou le fer \u00e0 repasser \u00e0 vapeur ont tous franchi cette \u00e9tape avant de conqu\u00e9rir le monde. Statistiquement, pr\u00e8s d&rsquo;une invention sur deux commercialis\u00e9e apr\u00e8s le concours trouve sa place sur le march\u00e9.<\/p>\n<p>Les autres laur\u00e9ats de cette \u00e9dition 2026 illustrent la diversit\u00e9 des besoins. Cl\u00e9ment Mignani, Lo\u00efc Folgoas et Pascal Migeot de Baran ont remport\u00e9 le troisi\u00e8me prix avec Securpost, un capteur install\u00e9 dans les bo\u00eetes aux lettres qui d\u00e9tecte les d\u00e9p\u00f4ts et retraits de courrier. Une notification est envoy\u00e9e \u00e0 l&rsquo;utilisateur. Quant au deuxi\u00e8me prix, il a \u00e9t\u00e9 attribu\u00e9 \u00e0 des skis \u00e9lectriques sur roues.<\/p>\n<\/div>\n<p><script>(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = \"\/\/connect.facebook.net\/fr_FR\/sdk.js#xfbml=1&version=v2.3\";  fjs.parentNode.insertBefore(js, fjs);}(document, \"script\", \"facebook-jssdk\"));<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.francesoir.fr\/societe-environnement\/un-aspirateur-sous-marin-remporte-le-concours-lepine-2026\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les 250 inventions pr\u00e9sent\u00e9es le dimanche 10 mai \u00e0 la Foire de Paris, il y en a une qui a capt\u00e9 l&rsquo;attention du jury pour sa port\u00e9e \u00e9cologique et&hellip; <\/p>\n","protected":false},"author":1,"featured_media":27751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=27750"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/27751"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=27750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=27750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=27750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}