{"id":27759,"date":"2026-05-13T06:06:37","date_gmt":"2026-05-13T04:06:37","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/le-conducteur-de-suv-qui-a-ecrase-le-cycliste-paul-varry-sera-juge-pour-meurtre\/"},"modified":"2026-05-13T06:06:37","modified_gmt":"2026-05-13T04:06:37","slug":"le-conducteur-de-suv-qui-a-ecrase-le-cycliste-paul-varry-sera-juge-pour-meurtre","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/le-conducteur-de-suv-qui-a-ecrase-le-cycliste-paul-varry-sera-juge-pour-meurtre\/","title":{"rendered":"Le conducteur de SUV qui a \u00e9cras\u00e9 le cycliste Paul Varry sera jug\u00e9 pour meurtre"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/paul_varry-92d77.jpg?1778602086\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>L&rsquo;automobiliste qui a \u00e9cras\u00e9 le cycliste Paul Varry sera jug\u00e9 pour meurtre devant la cour d&rsquo;assises. Telle est la d\u00e9cision de la magistrate qui a instruit le dossier, a appris le 12\u00a0mai Le Parisien. <br class=\"autobr\" \/><br \/>\nLe drame remonte au 15\u00a0octobre 2024, \u00e0 Paris. En fin de journ\u00e9e, en retard pour d\u00e9poser sa fille \u00e0 un rendez-vous m\u00e9dical, Ariel M.\u00a0avait emprunt\u00e9 la bande r\u00e9serv\u00e9e aux cyclistes avec son <span class=\"caps\">SUV<\/span> Mercedes. Selon plusieurs t\u00e9moins, le pneu de sa voiture serait entr\u00e9 en contact avec le pied de Paul\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Le-conducteur-de-SUV-qui-a-ecrase-le-cycliste-Paul-Varry-sera-juge-pour-meurtre?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Breves-20\" rel=\"directory\">En bref<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Transports\" rel=\"tag\">Transports<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Justice\" rel=\"tag\">Justice<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/Le-conducteur-de-SUV-qui-a-ecrase-le-cycliste-Paul-Varry-sera-juge-pour-meurtre\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;automobiliste qui a \u00e9cras\u00e9 le cycliste Paul Varry sera jug\u00e9 pour meurtre devant la cour d&rsquo;assises. Telle est la d\u00e9cision de la magistrate qui a instruit le dossier, a appris&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27759","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=27759"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27759\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=27759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=27759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=27759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}