{"id":27774,"date":"2026-05-13T14:54:40","date_gmt":"2026-05-13T12:54:40","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/a69-atosca-le-concessionnaire-de-lautoroute-perquisitionne\/"},"modified":"2026-05-13T14:54:40","modified_gmt":"2026-05-13T12:54:40","slug":"a69-atosca-le-concessionnaire-de-lautoroute-perquisitionne","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/05\/13\/a69-atosca-le-concessionnaire-de-lautoroute-perquisitionne\/","title":{"rendered":"A69\u00a0: Atosca, le concessionnaire de l&#039;autoroute, perquisitionn\u00e9"},"content":{"rendered":"<p> <br \/>\n<br \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/capture_d_ecran_du_2026-05-13_11-44-27-c4ec2.png?1778674273\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Est-ce le d\u00e9but de la fin pour le chantier de l&rsquo;A69<small class=\"fine d-inline\">\u00a0<\/small>? Le procureur de la R\u00e9publique de Toulouse a annonc\u00e9 le 12\u00a0mai avoir perquisitionn\u00e9 la veille les locaux d&rsquo;Atosca, concessionnaire de la future autoroute. Cette op\u00e9ration fait suite \u00e0 la plainte d\u00e9pos\u00e9e le 10\u00a0d\u00e9cembre par l&rsquo;association France Nature Environnement. Elle d\u00e9non\u00e7ait l&#8217;emprise d&rsquo;au moins 86\u00a0hectares de terres en dehors du p\u00e9rim\u00e8tre l\u00e9gal. Soit un d\u00e9passement de plus de 20<small class=\"fine d-inline\">\u00a0<\/small>% par rapport \u00e0 la surface initialement autoris\u00e9e. <br class=\"autobr\" \/><br \/>\nUne\u00a0(\u2026)<\/p>\n<p>                    <a target=\"_blank\" href=\"https:\/\/reporterre.net\/A69-les-locaux-du-concessionnaire-de-l-autoroute-ont-ete-perquisitionnes?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Breves-20\" rel=\"directory\">En bref<\/a><\/p>\n<p>                    \/<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/Autoroutes\" rel=\"tag\">Autoroutes<\/a><br \/>\n                    ,<br \/>\n                        <a target=\"_blank\" href=\"https:\/\/reporterre.net\/A69\" rel=\"tag\">A69<\/a><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/reporterre.net\/A69-les-locaux-du-concessionnaire-de-l-autoroute-ont-ete-perquisitionnes\" target=\"_blank\"\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est-ce le d\u00e9but de la fin pour le chantier de l&rsquo;A69\u00a0? Le procureur de la R\u00e9publique de Toulouse a annonc\u00e9 le 12\u00a0mai avoir perquisitionn\u00e9 la veille les locaux d&rsquo;Atosca, concessionnaire&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27774","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=27774"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/27774\/revisions"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=27774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=27774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=27774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}