{"id":29991,"date":"2026-07-15T01:20:59","date_gmt":"2026-07-14T23:20:59","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/la-dgs-rappelle-que-leau-du-robinet-nest-plus-potable-si-elle-depasse-les-25c\/"},"modified":"2026-07-15T01:20:59","modified_gmt":"2026-07-14T23:20:59","slug":"la-dgs-rappelle-que-leau-du-robinet-nest-plus-potable-si-elle-depasse-les-25c","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/la-dgs-rappelle-que-leau-du-robinet-nest-plus-potable-si-elle-depasse-les-25c\/","title":{"rendered":"La DGS rappelle que l&#039;eau du robinet n&#039;est plus potable si elle d\u00e9passe les 25\u00b0C"},"content":{"rendered":"<p>Fin juin, dans un immeuble du 19e arrondissement de Paris, l&rsquo;eau froide a coul\u00e9 \u00e0 33 \u00b0C en pleine vague de chaleur.<\/p>\n<p class=\"verinews-source\">Source : <a href=\"https:\/\/www.francesoir.fr\/societe-sante\/la-dgs-rappelle-que-l-eau-du-robinet-n-est-plus-potable-si-elle-depasse-les-25degc\" target=\"_blank\" rel=\"nofollow noopener\">Lire l\u2019article original<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin juin, dans un immeuble du 19e arrondissement de Paris, l&rsquo;eau froide a coul\u00e9 \u00e0 33 \u00b0C en pleine vague de chaleur.<\/p>\n","protected":false},"author":1,"featured_media":27996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/29991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=29991"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/29991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/27996"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=29991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=29991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=29991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}