{"id":30008,"date":"2026-07-15T12:00:57","date_gmt":"2026-07-15T10:00:57","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/pesticides-interdits-le-gouvernement-offre-un-consentement-a-lempoisonnement-alimentaire-de-la-population\/"},"modified":"2026-07-15T12:00:57","modified_gmt":"2026-07-15T10:00:57","slug":"pesticides-interdits-le-gouvernement-offre-un-consentement-a-lempoisonnement-alimentaire-de-la-population","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/pesticides-interdits-le-gouvernement-offre-un-consentement-a-lempoisonnement-alimentaire-de-la-population\/","title":{"rendered":"Pesticides interdits\u00a0: \u00ab\u00a0Le gouvernement offre un consentement \u00e0 l&#039;empoisonnement alimentaire de la population\u00a0\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/dscf4120_1_-4-2-f9e59.jpg?1784093402\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Des aliments contamin\u00e9s au-del\u00e0 des seuils par des pesticides interdits en Europe, dont du riz Lustucru et des \u00e9pices Ducros, sont toujours dans les rayons. En cause, l&rsquo;inaction de l&rsquo;\u00c9tat et le poids des industries. <br class=\"autobr\" \/> Du th\u00e9 vert, des \u00e9pices et du riz qui contiennent des pesticides interdits en Europe sont toujours vendus dans les supermarch\u00e9s fran\u00e7ais plus d&rsquo;un mois apr\u00e8s l&rsquo;alerte lanc\u00e9e par l&rsquo;<span class=\"caps\">ONG<\/span> Foodwatch. Le 19\u00a0mai, elle a rendu publics les r\u00e9sultats accablants des analyses command\u00e9es \u00e0\u00a0(\u2026)<\/p>\n<p>                    <a href=\"https:\/\/reporterre.net\/Pesticides-interdits-Le-gouvernement-offre-un-consentement-a-l-empoisonnement-alimentaire?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a href=\"https:\/\/reporterre.net\/Enquete\" rel=\"directory\">Enqu\u00eate<\/a><\/p>\n<p>                    \/<br \/>\n                        <a href=\"https:\/\/reporterre.net\/Pesticides\" rel=\"tag\">Pesticides<\/a><br \/>\n                    ,<br \/>\n                        <a href=\"https:\/\/reporterre.net\/Sante\" rel=\"tag\">Sant\u00e9<\/a><\/p>\n<p class=\"verinews-source\">Source : <a href=\"https:\/\/reporterre.net\/Pesticides-interdits-Le-gouvernement-offre-un-consentement-a-l-empoisonnement-alimentaire\" target=\"_blank\" rel=\"nofollow noopener\">Lire l\u2019article original<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des aliments contamin\u00e9s au-del\u00e0 des seuils par des pesticides interdits en Europe, dont du riz Lustucru et des \u00e9pices Ducros, sont toujours dans les rayons. En cause, l&rsquo;inaction de l&rsquo;\u00c9tat et le poids des industries.\u2026<\/p>\n","protected":false},"author":1,"featured_media":27996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/30008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=30008"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/30008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/27996"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=30008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=30008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=30008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}