{"id":30013,"date":"2026-07-15T14:41:06","date_gmt":"2026-07-15T12:41:06","guid":{"rendered":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/avec-leur-potager-pirate-les-habitants-de-ce-quartier-populaire-se-reapproprient-leur-terre\/"},"modified":"2026-07-15T14:41:06","modified_gmt":"2026-07-15T12:41:06","slug":"avec-leur-potager-pirate-les-habitants-de-ce-quartier-populaire-se-reapproprient-leur-terre","status":"publish","type":"post","link":"https:\/\/monde25.info\/index.php\/2026\/07\/15\/avec-leur-potager-pirate-les-habitants-de-ce-quartier-populaire-se-reapproprient-leur-terre\/","title":{"rendered":"Avec leur potager \u00ab\u00a0pirate\u00a0\u00bb, les habitants de ce quartier populaire se r\u00e9approprient leur terre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/reporterre.net\/local\/cache-vignettes\/L700xH467\/jardinabagnolet-35b3a.jpg?1784093402\" class=\"spip_logo\" width=\"700\" height=\"467\" alt=\"\" \/><\/p>\n<p>Des pommes de terre et des haricots au pied des immeubles, des salades dans les jardini\u00e8res&#8230; Dans le quartier de La Noue, \u00e0 Bagnolet, les habitants r\u00e9cup\u00e8rent un peu de terre au c\u0153ur du b\u00e9ton. <br class=\"autobr\" \/> Cet article est extrait du num\u00e9ro de juin 2026 du journal L&rsquo;\u00c2ge de faire. Canard joyeux mais pas na\u00eff, L&rsquo;\u00c2ge de faire est un mensuel ind\u00e9pendant et sans publicit\u00e9. \u00c9dit\u00e9 par une coop\u00e9rative de presse, il est diffus\u00e9 partout en France, \u00e0 petit prix. <br class=\"autobr\" \/><br \/>\nBagnolet (Seine-Saint-Denis), reportage <br class=\"autobr\" \/><br \/>\nLes\u00a0(\u2026)<\/p>\n<p>                    <a href=\"https:\/\/reporterre.net\/Avec-leur-potager-pirate-les-habitants-de-ce-quartier-populaire-se-reapproprient-leur?utm_source=RSS&amp;utm_medium=RSS\">Lire la suite<\/a><\/p>\n<p>                    &#8211;<br \/>\n                        <a href=\"https:\/\/reporterre.net\/Reportage\" rel=\"directory\">Reportage<\/a><\/p>\n<p>                    \/<br \/>\n                        <a href=\"https:\/\/reporterre.net\/Climat-et-quartiers-populaires\" rel=\"tag\">Climat et quartiers populaires<\/a><\/p>\n<p class=\"verinews-source\">Source : <a href=\"https:\/\/reporterre.net\/Avec-leur-potager-pirate-les-habitants-de-ce-quartier-populaire-se-reapproprient-leur\" target=\"_blank\" rel=\"nofollow noopener\">Lire l\u2019article original<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des pommes de terre et des haricots au pied des immeubles, des salades dans les jardini\u00e8res&#8230; Dans le quartier de La Noue, \u00e0 Bagnolet, les habitants r\u00e9cup\u00e8rent un peu de terre au c\u0153ur du b\u00e9ton.\u2026<\/p>\n","protected":false},"author":1,"featured_media":27996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/30013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/comments?post=30013"}],"version-history":[{"count":0,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/posts\/30013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media\/27996"}],"wp:attachment":[{"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/media?parent=30013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/categories?post=30013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monde25.info\/index.php\/wp-json\/wp\/v2\/tags?post=30013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}